{"id":222,"date":"2017-03-23T17:20:09","date_gmt":"2017-03-23T16:20:09","guid":{"rendered":"http:\/\/themenectar.com\/demo\/salient\/?p=110"},"modified":"2020-07-08T14:47:05","modified_gmt":"2020-07-08T12:47:05","slug":"ma-vie-a-singapour","status":"publish","type":"post","link":"https:\/\/guillaumeteillet.com\/en\/ma-vie-a-singapour\/","title":{"rendered":"\ud83c\uddf8\ud83c\uddecMa vie \u00e0 Singapour"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 32<\/span> <span class=\"rt-label rt-postfix\">minutes<br \/><br \/><\/span><\/span>\n\t\t<div id=\"fws_6a04774cb87da\"  data-column-margin=\"default\" data-midnight=\"dark\"  data-bg-mobile-hidden=\"\" class=\"wpb_row vc_row-fluid vc_row standard_section\"  style=\"padding-top: 20px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay\" ><\/div><\/div><div class=\"col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding\"  data-t-w-inherits=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-border-animation=\"\" data-border-animation-delay=\"\" data-border-width=\"none\" data-border-style=\"solid\" data-border-color=\"\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p><em>\u00c0 l&#8217;origine je devais y rester 6 mois : j&#8217;y ai v\u00e9cu pendant quasiment 4 ans. Dans cet article, je vous parle de ma vie \u00e0 Singapour, cette cit\u00e9-\u00c9tat au sud de la Malaisie.<\/em><\/p>\n<h2>I &#8211; Mon arriv\u00e9e \u00e0 Singapour<\/h2>\n<p>J&#8217;ai d\u00e9barqu\u00e9 \u00e0 Singapour pour la premi\u00e8re fois le 5 mai 2016 apr\u00e8s avoir d\u00e9croch\u00e9 mon stage de fin d&#8217;\u00e9tudes dans une entreprise de services de programmation informatique. Mathieu, <a href=\"https:\/\/guillaumeteillet.com\/en\/mon-annee-en-chine\/\">qui \u00e9tait aussi avec moi en Chine<\/a>, avait \u00e9galement obtenu un stage dans la m\u00eame entreprise.<\/p>\n<p>Notre avion a atterri \u00e0 Singapour 6 heures du matin. La premi\u00e8re chose qui nous a impressionn\u00e9s, c&#8217;est la beaut\u00e9 et l&#8217;efficacit\u00e9 de l&#8217;a\u00e9roport de Changi : ce n&#8217;est pas pour rien qu&#8217;il a \u00e9t\u00e9 \u00e9lu pendant 5 ans cons\u00e9cutifs comme \u00e9tant l&#8217;a\u00e9roport le plus beau du monde.<\/p>\n<p>En quelques minutes, nous avions r\u00e9cup\u00e9r\u00e9 nos bagages, passer l&#8217;immigration, et nous \u00e9tions dans un taxi pour nous rendre \u00e0 l&#8217;h\u00f4tel.<\/p>\n<p>Nos premiers pas \u00e0 l&#8217;ext\u00e9rieur de l&#8217;a\u00e9roport nous ont rappel\u00e9 que nous venions d&#8217;arriver dans un pays tropical : la chaleur \u00e9tait \u00e9touffante et l&#8217;humidit\u00e9 bien pr\u00e9sente alors que le pays commen\u00e7ait \u00e0 se r\u00e9veiller doucement.<\/p>\n<p>Apr\u00e8s avoir d\u00e9pos\u00e9 nos affaires \u00e0 l&#8217;h\u00f4tel, nous avons commenc\u00e9 \u00e0 visiter des appartements \u00e0 louer. En effet, quelques semaines avant mon arriv\u00e9e, j&#8217;avais pris contact avec des propri\u00e9taires afin d&#8217;en visiter plusieurs d\u00e8s le premier jour et de ne pas perdre trop de temps \u00e0 l&#8217;h\u00f4tel.<\/p>\n<p>Cette strat\u00e9gie s&#8217;est av\u00e9r\u00e9e payante puisque d\u00e8s 19 heures, le premier jour, nous avons sign\u00e9 un bail pour 6 mois de colocation.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items no-masonry\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160505_170818-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160505_170818-scaled.jpg\" title=\"L'appartement \u00e0 Geylang\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160505_171214-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160505_171214-scaled.jpg\" title=\"La piscine de la r\u00e9sidence\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160505_170921-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160505_170921-scaled.jpg\" title=\"L'appartement \u00e0 Geylang\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Mon premier appartement en colocation au centre de Singapour (Geylang)<\/em><\/p>\n<h2>II &#8211; Les logements<\/h2>\n<p>Dans cet article, je vais uniquement parler de la location d&#8217;un logement \u00e0 Singapour, car c&#8217;est d\u00e9j\u00e0 un sujet tr\u00e8s vaste.<\/p>\n<p>Il existe de plusieurs types de logements :<\/p>\n<ul>\n<li>Les condos<\/li>\n<li>Les HDB<\/li>\n<li>Les maisons<\/li>\n<\/ul>\n<h4><span style=\"text-decoration: underline;\">a) Les condos<\/span><\/h4>\n<p>Il s&#8217;agit d&#8217;immeubles de luxe qui dispose d&#8217;\u00e9quipement \u00e0 la disposition des r\u00e9sidents (piscines, salles de sport, aire de jeux pour les enfants&#8230;) mais aussi de gardiens. Il ne repr\u00e9sente que 10% du parc immobilier \u00e0 Singapour mais c&#8217;est l&#8217;option retenue par une majorit\u00e9 d&#8217;\u00e9trangers.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items no-masonry\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-2\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_6  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/cheap-accessible-condos-rent-singapore-double-bay-residences-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/cheap-accessible-condos-rent-singapore-double-bay-residences.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_6  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/Screen-Shot-2018-10-16-at-6.56.07-PM-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/Screen-Shot-2018-10-16-at-6.56.07-PM.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Exemples de condos<\/em><\/p>\n<p>Il existe deux types de condos : les petits et les grands.<\/p>\n<p><strong>LES PETITS CONDOS<\/strong><\/p>\n<p>Les petits condos comportent tr\u00e8s peu d&#8217;appartements et ceux-ci sont en g\u00e9n\u00e9ral plus petits que dans les grands condos (du studio au 3 pi\u00e8ces).<\/p>\n<p>Ils sont souvent moins chers (mais pas toujours) car il y a moins de frais de maintenance et il n&#8217;y a pas de gardiens \u00e0 payer. Ils sont aussi plus calme car il y a moins de r\u00e9sidents.<\/p>\n<p>En revanche, ils poss\u00e8dent \u00e9galement moins d&#8217;\u00e9quipements : la piscine est plus petite, la &#8220;salle de sports&#8221; contient g\u00e9n\u00e9ralement qu&#8217;un tapis de course ou un v\u00e9lo d&#8217;appartement et il est tr\u00e8s rare d&#8217;y trouver des barbecues et des salles de r\u00e9ception.<\/p>\n<p>En cas de panne d&#8217;un \u00e9quipement, il faudra souvent attendre plus longtemps que dans un grand condo car le management (le syndic) n&#8217;a pas de bureau dans le condo.<\/p>\n<p><strong>LES GRANDS CONDOS<\/strong><\/p>\n<p>Les grands condos sont les plus nombreux \u00e0 Singapour. Dans ces r\u00e9sidences qui comportent des centaines d&#8217;appartements, vous aurez tr\u00e8s souvent la possibilit\u00e9 de visiter plusieurs appartements avant de choisir celui qui vous convient.<\/p>\n<p>Les grands condos proposent g\u00e9n\u00e9ralement beaucoup d&#8217;\u00e9quipement : une ou plusieurs piscines, des terrains de tennis, des salles de sports, des barbecues, des salles que vous pouvez r\u00e9server pour inviter vos amis&#8230; Certains d&#8217;entre eux sont de v\u00e9ritables mini-villes avec, pour les plus chers, des \u00e9quipements luxueux : salle de cin\u00e9ma que vous pouvez r\u00e9server pour regarder un film avec votre famille ou vos amis, mini-golf, karaok\u00e9&#8230;<\/p>\n<p>Ils ont aussi beaucoup plus de r\u00e8gles \u00e0 respecter que dans les petits condos. Les gardiens et le management (syndic) veillent jour et nuit au respect de celles-ci.<\/p>\n<p>Les grands condos sont aussi beaucoup plus bruyants que les petits car il y a plus de r\u00e9sidents.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h4><span style=\"text-decoration: underline;\">b) Les HDB<\/span><\/h4>\n<p>C&#8217;est la grande majorit\u00e9 du parc immobilier (85%). Souvent compar\u00e9s aux HLM fran\u00e7ais, les HDB ont un loyer beaucoup plus faible car ils ne poss\u00e8dent pas d&#8217;\u00e9quipements pour les r\u00e9sidents.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items no-masonry\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-2\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_6  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/HDB-Responds-to-Need-for-Flexible-Flat-Layouts-in-Singapore-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/HDB-Responds-to-Need-for-Flexible-Flat-Layouts-in-Singapore.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_6  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/4749573658_e0913bf475_b-600x400.jpg\" width=\"600\" height=\"400\" alt=\"4749573658_e0913bf475_b\" title=\"4749573658_e0913bf475_b\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/4749573658_e0913bf475_b.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Exemples de HDB<\/em><\/p>\n<p>Dans les HDB, vous pouvez faire une croix sur la piscine et les barbecues. En revanche, il n&#8217;est pas rare d&#8217;avoir plus d&#8217;espace dans l&#8217;appartement pour moins cher.<\/p>\n<p>Majoritairement boud\u00e9s par les \u00e9trangers qui pr\u00e9f\u00e8rent les condos ou les maisons, les r\u00e9sidents des HDB sont pour la plupart Singapouriens.<\/p>\n<p>Certaines races de chiens sont autoris\u00e9es dans les HDB (\u00e0 confirmer avec votre propri\u00e9taire bien s\u00fbr), mais les chats sont pour l&#8217;instant toujours interdits.<\/p>\n<p><strong>HDB CLASSIQUE<\/strong><\/p>\n<p>Les premiers HDB ont \u00e9t\u00e9 construits \u00e0 partir des ann\u00e9es 1960. Autant dire que les go\u00fbts et les couleurs de cette \u00e9poque ne sont plus ceux d&#8217;aujourd&#8217;hui et que si l&#8217;appartement n&#8217;a pas \u00e9t\u00e9 r\u00e9nov\u00e9, vous aurez peut-\u00eatre l&#8217;impression de vivre en URSS.<\/p>\n<p>Vous n&#8217;aurez tr\u00e8s probablement de balcon puisqu&#8217;ils ne sont apparus dans les HDB qu&#8217;\u00e0 partir des ann\u00e9es 2015-2016.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"800\" width=\"1200\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/177fcda6-a2bc-11e9-9a3c-98259c87fba2_972x_181251.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/177fcda6-a2bc-11e9-9a3c-98259c87fba2_972x_181251.jpg 1200w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/177fcda6-a2bc-11e9-9a3c-98259c87fba2_972x_181251-300x200.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/177fcda6-a2bc-11e9-9a3c-98259c87fba2_972x_181251-1024x683.jpg 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/177fcda6-a2bc-11e9-9a3c-98259c87fba2_972x_181251-768x512.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/177fcda6-a2bc-11e9-9a3c-98259c87fba2_972x_181251-900x600.jpg 900w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>HDB Classique &#8211; Image d&#8217;internet<\/em><\/p>\n<p><strong>HDB R\u00c9NOV\u00c9<\/strong><\/p>\n<p>De plus en plus nombreux, les HDB r\u00e9nov\u00e9s permettent d&#8217;avoir un int\u00e9rieur plus actuel tout en gardant un loyer raisonnable.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"720\" width=\"951\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/standard.jpeg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/standard.jpeg 951w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/standard-300x227.jpeg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/standard-768x581.jpeg 768w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>HDB R\u00e9nov\u00e9 &#8211; Image d&#8217;internet<\/em><\/p>\n<p>L\u00e0 encore, peu de chance d&#8217;avoir un balcon : ils y en avaient pas avant les ann\u00e9es 2015-2016.<\/p>\n<p><strong>HDB NEW GENERATION<\/strong><\/p>\n<p>Depuis quelques ann\u00e9es, le gouvernement a d\u00e9cid\u00e9 d&#8217;arr\u00eater la production de HDB &#8220;dortoir&#8221; pour proposer des HDB un peu plus esth\u00e9tiques : ils ont d\u00e9sormais des balcons et ils sont pens\u00e9s de fa\u00e7on \u00e0 \u00eatre adapt\u00e9 \u00e0 la vie d&#8217;aujourd&#8217;hui.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"399\" width=\"600\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/HDB-a-Punggol-Singapour.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/HDB-a-Punggol-Singapour.jpg 600w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/HDB-a-Punggol-Singapour-300x200.jpg 300w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>HDB New Generation &#8211; Image d&#8217;internet<\/em><\/p>\n<p>Si pour vous le balcon n&#8217;est pas une option, alors le HDB devra \u00eatre plut\u00f4t r\u00e9cent et les HDB New Generation sont donc ce que vous recherchez.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h4><span style=\"text-decoration: underline;\">c) Les maisons<\/span><\/h4>\n<p>Singapour est une \u00eele &#8211; cela ne vous aura pas \u00e9chapp\u00e9 &#8211; et par cons\u00e9quent, les maisons sont rares par manque de place. Elles repr\u00e9sentent environ 5% du parc immobilier singapourien et les loyers sont extr\u00eamement chers.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items no-masonry\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-2\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_6  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/maison-coloniale-singapour-15-740x493-1-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/maison-coloniale-singapour-15-740x493-1.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_6  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/House-With-Screens-by-ADX-Architects-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/House-With-Screens-by-ADX-Architects.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Exemples de maisons<\/em><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h4><span style=\"text-decoration: underline;\">d) Mon exp\u00e9rience personnelle<\/span><\/h4>\n<p>En quasiment 4 ans \u00e0 Singapour, j&#8217;ai v\u00e9cu dans 3 logements diff\u00e9rents, uniquement dans des condos (1 petit et 2 grands).<\/p>\n<p>\u00c0 titre purement informatif, je vais indiquer dans quels condos j&#8217;ai v\u00e9cu et quel \u00e9tait le prix du loyer : cela pourra peut-\u00eatre aider quelques personnes dans leurs recherches de logement \u00e0 Singapour.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>CENTRA LOFT &#8211; GEYLANG<\/strong><\/span><\/p>\n<p>C&#8217;est un petit condo qui se situe \u00e0 Geylang, pas tr\u00e8s loin du centre \u00e9conomique de Singapour. Il n&#8217;est pas tr\u00e8s loin du m\u00e9tro (5 minutes de marche).<\/p>\n<p><strong>Nombre de chambres : <\/strong>2<br \/>\n<strong>Nombre de salles de bain :<\/strong> 1<br \/>\n<strong>\u00c9quipements :<\/strong> Une seule piscine et une minuscule salle de sport.<strong><br \/>\nQuartier :<\/strong> Geylang<br \/>\n<strong>Loyer :<\/strong> 2500 SGD par mois (environ 1592 euros)<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items no-masonry\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/46392-550x400.jpg\" width=\"550\" height=\"400\" alt=\"Centra Loft\" title=\"Centra Loft\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/46392.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/1341502.jpg\" width=\"550\" height=\"399\" alt=\"Centra Loft\" title=\"Centra Loft\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/1341502.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/1_plus_study_for_rent__centra_loft_1522218877_e131e1b43-1-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/1_plus_study_for_rent__centra_loft_1522218877_e131e1b43-1.jpg\" title=\"Cuisine Centra Loft\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/centra_loft_1553822612_6704f158_progressive-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/centra_loft_1553822612_6704f158_progressive.jpg\" title=\"Balcon Centra Loft\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/centra_loft_1553822612_2be038f0_progressive-600x400.jpg\" width=\"600\" height=\"400\" alt=\"Salon  Centra Loft\" title=\"Salon  Centra Loft\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/centra_loft_1553822612_2be038f0_progressive.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/centra_loft_1553822612_a90a12da_progressive-600x400.jpg\" width=\"600\" height=\"400\" alt=\"Salle de bain Centra Loft\" title=\"Salle de bain Centra Loft\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/centra_loft_1553822612_a90a12da_progressive.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p><span style=\"text-decoration: underline;\"><strong>A TREASURE TROVE &#8211; PUNGGOL<\/strong><\/span><\/p>\n<p>Tr\u00e8s \u00e9loign\u00e9 du centre de Singapour, ce condo \u00e0 l&#8217;avantage d&#8217;\u00eatre proche d&#8217;un centre commercial et \u00e0 moins de 3 minutes de marche du m\u00e9tro.<\/p>\n<p><strong>Nombre de chambres : <\/strong>3<br \/>\n<strong>Nombre de salles de bain :<\/strong> 3<br \/>\n<strong>\u00c9quipements :<\/strong> 3 piscines olympiques, une salle de sport, 3 salles r\u00e9servable, un sauna, des jeux pour enfants, des barbecues, un jacuzzi.<br \/>\n<strong>Quartier :<\/strong> Punggol<br \/>\n<strong>Loyer :<\/strong> 2800 SGD par mois (environ 1783 euros)<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items no-masonry\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20161015_122751-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20161015_122751.jpg\" title=\"A Treasure Trove\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20161221_095107-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20161221_095107.jpg\" title=\"Salon du condo A Treasure Trove\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20161015_124011-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20161015_124011.jpg\" title=\"Une des piscines du condo A Treasure Trove\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20161015_123958-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20161015_123958.jpg\" title=\"Barbecues du condo A Treasure Trove\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20161015_123019-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20161015_123019.jpg\" title=\"Le Club House du condo A Treasure Trove\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20161221_095049-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20161221_095049.jpg\" title=\"Cuisine A Treasure Trove\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p><span style=\"text-decoration: underline;\"><strong>WATERTOWN &#8211; PUNGGOL<\/strong><\/span><\/p>\n<p>Situ\u00e9 au-dessus d&#8217;un centre commercial (ouvert 24h\/24) et juste \u00e0 c\u00f4t\u00e9 du m\u00e9tro ce condo est vraiment tr\u00e8s pratique. De l&#8217;ext\u00e9rieur, il n&#8217;a pas l&#8217;air tr\u00e8s int\u00e9ressant, mais l&#8217;int\u00e9rieur est vraiment bien.<\/p>\n<p><strong>Nombre de chambres :<\/strong> 1<strong><br \/>\nNombre de salles de bain :<\/strong> 1<br \/>\n<strong>\u00c9quipements : <\/strong>Une vingtaine de piscines, une salle de sport, un sauna, un jacuzzi, des jeux pour enfants, des barbecues, 1 salle r\u00e9servable.<strong><br \/>\nQuartier :<\/strong> Punggol<br \/>\n<strong>Loyer :<\/strong> 2400 SGD par mois (environ 1530 euros)<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items no-masonry\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/Watertown-3-Bed-pool-e1540970667210-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/Watertown-3-Bed-pool-e1540970667210.jpg\" title=\"Une piscine \u00e0 Watertown\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/watertown__punggol_mrt_3br_1524330093_1b22ccf1-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/watertown__punggol_mrt_3br_1524330093_1b22ccf1.jpg\" title=\"Une piscine \u00e0 Watertown\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/2552e26094c14d65476ab6ba546c6572cba466ed-scaled-600x400.jpeg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/2552e26094c14d65476ab6ba546c6572cba466ed-scaled.jpeg\" title=\"Une piscine \u00e0 Watertown\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/1-scaled-600x400.jpeg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/1-scaled.jpeg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/photo_2020-05-31_09-44-18-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/photo_2020-05-31_09-44-18.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/watertown_1583856742_ebe5d2d8e_progressive-600x400.jpeg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/watertown_1583856742_ebe5d2d8e_progressive.jpeg\" title=\"Cuisine Watertown\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>III &#8211; Le monde de l&#8217;entreprise<\/h2>\n<p>Singapour est un carrefour international au coeur de l&#8217;Asie : toutes les nationalit\u00e9s, les cultures et les religions sont pr\u00e9sentes sur l&#8217;\u00eele. Par exemple, dans l&#8217;entreprise qui m&#8217;employait, nous avions plus de 35 nationalit\u00e9s repr\u00e9sent\u00e9es !<\/p>\n<p>Heureusement, l&#8217;anglais est la langue principale de l&#8217;\u00eele : il n&#8217;est absolument pas n\u00e9cessaire de parler le chinois Mandarin (cela peut toutefois \u00eatre un avantage selon votre m\u00e9tier)<\/p>\n<p>Dans cette partie, je vais parler uniquement de mon exp\u00e9rience personnelle du monde de l&#8217;entreprise \u00e0 Singapour. Mon exp\u00e9rience est certainement tr\u00e8s diff\u00e9rente de celle d&#8217;un \u00e9tranger qui travaille dans le secteur de la Construction ou dans le domaine de la Finance.<\/p>\n<p>Pendant 3 ans, j&#8217;ai travaill\u00e9 comme consultant dans une soci\u00e9t\u00e9 de services en informatique : cette exp\u00e9rience m&#8217;a permis de d\u00e9couvrir le fonctionnement de plusieurs entreprises singapouriennes mais aussi plus internationales.<\/p>\n<h4><span style=\"text-decoration: underline;\"><strong>Les entreprises singapouriennes<\/strong><\/span><\/h4>\n<p>Les entreprises singapouriennes sont largement influenc\u00e9es par la culture traditionnelle chinoise car l&#8217;ethnie chinoise est largement majoritaire* \u00e0 Singapour (75% des Singapouriens appartiennent \u00e0 cette ethnie).<\/p>\n<p>En pratique cela se traduit par une hi\u00e9rarchie tr\u00e8s rigide : pas question de d\u00e9battre ou de remettre en question les id\u00e9es d&#8217;un sup\u00e9rieur ! Le chef \u00e0 raison, m\u00eame quand il a tord : dans la culture chinoise, il ne faut surtout pas faire &#8220;perdre la face&#8221; \u00e0 son interlocuteur.<\/p>\n<p>Dans la majorit\u00e9 des entreprises singapouriennes, le temps de travail officiel se situe entre 40 et 45 heures par semaines. En pratique, les Singapouriens restent souvent beaucoup plus longtemps sur leur lieu de travail car la culture du pr\u00e9sent\u00e9isme est bien ancr\u00e9e dans les moeurs : il est tr\u00e8s mal vu de partir avant son patron.<\/p>\n<p><em>* A Singapour, les statistiques ethniques sont publiques et ne sont absolument pas tabou.<\/em><\/p>\n<h4><span style=\"text-decoration: underline;\">Les entreprises internationales<\/span><\/h4>\n<p>Dans les entreprises internationales, la plupart du temps, les managers ne sont pas tous singapouriens : cela se traduit par une culture d&#8217;entreprise assez diff\u00e9rente des entreprises locales mais qui se rapproche beaucoup de celle des entreprises am\u00e9ricaines et europ\u00e9ennes.<\/p>\n<p>Concr\u00e8tement, il est beaucoup plus facile d&#8217;exprimer et de d\u00e9battre d&#8217;une opinion contraire dans les entreprises internationales. Elles seront \u00e9galement plus sensibles au bien-\u00eatre de leurs salari\u00e9s sur leur lieu de travail.<\/p>\n<p>En tant que consultant, j&#8217;ai souvent remarqu\u00e9 une diff\u00e9rence dans les relations que j&#8217;entretenais avec les entreprises singapouriennes et internationales. Souvent, les entreprises singapouriennes ne cherchaient pas un consultant, mais un ex\u00e9cutant.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>IV &#8211; Les loisirs<\/h2>\n<p>De par sa taille, Singapour n&#8217;offre que tr\u00e8s peu d&#8217;attractions et de loisirs. Alors bien s\u00fbr, il y a des bars, des restaurants et des cin\u00e9mas mais apr\u00e8s plusieurs ann\u00e9es sur place, certaines personnes peuvent trouver Singapour ennuyante.<\/p>\n<p>Heureusement, la cit\u00e9-\u00c9tat est bien situ\u00e9e et les pays aux alentours sont accessibles en quelques heures d&#8217;avions.<\/p>\n<p>Dans cette partie, j&#8217;ai choisi de parler des lieux qui m\u00e9ritent votre attention si vous \u00eates de passage \u00e0 Singapour ou si vous venez d&#8217;arriver.<\/p>\n<h4><strong>Garden by the Bay<\/strong><\/h4>\n<p>Ouvert au public depuis juin 2012, Garden by the way est tr\u00e8s vite devenu un lieu embl\u00e9matique de Singapour. Il s&#8217;agit d&#8217;un immense jardin situ\u00e9 derri\u00e8re l&#8217;h\u00f4tel Marina Bay Sands.<\/p>\n<p><strong>Prix :<\/strong> L&#8217;acc\u00e8s au jardin est gratuit, en revanche, si vous souhaitez visiter les deux immenses d\u00f4mes (j&#8217;en parle un peu plus bas), alors vous devrez vous acquitter d&#8217;un droit d&#8217;entr\u00e9e.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"75%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1480\" width=\"1973\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_8773.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_8773.jpg 1973w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_8773-300x225.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_8773-1024x768.jpg 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_8773-768x576.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_8773-1536x1152.jpg 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Garden by the Bay vu depuis le Marina Bay Sands (voir plus bas)<\/em><\/p>\n<p><strong>Cloud Forest et Flower Dome<\/strong><\/p>\n<p>En plus du jardin ext\u00e9rieur, Garden by the Bay poss\u00e8de aussi 2 d\u00f4mes climatis\u00e9s : Cloud Forest et Flower Dome.<\/p>\n<p>Les entr\u00e9es \u00e0 ces deux d\u00f4mes sont payantes, mais si les fleurs vous int\u00e9ressent, alors vous ne serez pas d\u00e9\u00e7u.<\/p>\n<p><strong>Horaires :<\/strong> de 9h \u00e0 21h, tous les jours.<br \/>\n<strong>Prix touristes :<\/strong><\/p>\n<ul>\n<li>Les 2 d\u00f4mes : 28 SGD pour les adultes et 15 SGD pour les enfants (3 \u00e0 12 ans)<\/li>\n<\/ul>\n<p><strong>Prix r\u00e9sidents Singapour :\u00a0<\/strong><\/p>\n<ul>\n<li>Les 2 d\u00f4mes : 20 SGD pour les adultes, 15 SGD pour les 60 ans et plus et 12 SGD pour les enfants (3 \u00e0 12 ans)<\/li>\n<li>1 seul d\u00f4me : 12 SGD pour les adultes, 8 SGD pour les 60 ans et plus et 8 SGD pour les enfants (3 \u00e0 12 ans)<\/li>\n<\/ul>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"75%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"960\" width=\"1280\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_142432.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_142432.jpg 1280w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_142432-300x225.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_142432-1024x768.jpg 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_142432-768x576.jpg 768w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Selfie dans le Flower Dome<\/em><\/p>\n<p><strong>SuperTree Grove<\/strong><\/p>\n<p>Enfin, comment parler de Garden by the Bay sans abord\u00e9 ces immenses structures m\u00e9talliques en forme d&#8217;arbres : les SuperTree Grove.<\/p>\n<p>Si vous ne comprenez pas bien \u00e0 quoi servent ces structures, c&#8217;est que le r\u00e9sultat final n&#8217;est pas encore visible : l&#8217;objectif est que la v\u00e9g\u00e9tation enveloppe ces structures de m\u00e9tal pour cr\u00e9er une canop\u00e9e.<\/p>\n<p>Vous pouvez les observer gratuitement depuis le sol, seul l&#8217;acc\u00e8s au SkyWay est payant.<\/p>\n<p><strong>Horaires :<\/strong> De 9h \u00e0 21h tous les jours<br \/>\n<strong>Tarifs SkyWay :<\/strong> 8\u00a0SGD pour les adultes et 5 SGD pour les enfants (3 \u00e0 12 ans)<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"75%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1920\" width=\"2560\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_161558-scaled.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_161558-scaled.jpg 2560w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_161558-300x225.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_161558-1024x768.jpg 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_161558-768x576.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_161558-1536x1152.jpg 1536w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_161558-2048x1536.jpg 2048w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Le Skyway des SuperTree<\/em><\/p>\n<h4>CE LA VI<\/h4>\n<p>\u00c0 d\u00e9faut de pouvoir dormir au Marina Bay Sands et donc d&#8217;aller vous baigner dans leur c\u00e9l\u00e8bre piscine \u00e0 d\u00e9bordement, vous pourrez toujours vous offrir un verre avec une vue sublime sur Singapour et sur Garden by the bay en vous rendant au bar rooftop du Marina Bay Sands, le CE LA VI.<\/p>\n<p>Attention cependant : les prix sont un peu plus \u00e9lev\u00e9s que dans un bar classique et l&#8217;alcool est aussi tr\u00e8s cher \u00e0 Singapour (Pour avoir une id\u00e9e des prix des consommations, la bi\u00e8re (Stella Artois) est \u00e0 20 SGD soit environ 13 \u20ac et les jus de fruits sont \u00e0 12 SGD soit environ 8 \u20ac)<\/p>\n<p>Je vous recommande de monter vers 18 heures afin de profiter de la vue de jour et d\u2019assister au coucher de soleil. Vous pourrez ensuite admirer la ville de nuit.<\/p>\n<p><strong>Horaires du &#8220;Club Lounge&#8221; :<\/strong><\/p>\n<ul>\n<li><span class=\"contentful-rich-text\" data-v-0c843bd4=\"\"><span class=\"text\" data-v-0c843bd4=\"\">Lundi &amp; Mardi, de midi \u00e0 2h du matin (Derni\u00e8re entr\u00e9e \u00e0 1h45 du matin)<\/span><\/span><\/li>\n<li>Mercredi, Jeudi, Vendredi, de midi \u00e0 4h du matin <span class=\"contentful-rich-text\" data-v-0c843bd4=\"\"><span class=\"text\" data-v-0c843bd4=\"\">(Derni\u00e8re entr\u00e9e \u00e0 3h15 du matin)<\/span><\/span><\/li>\n<li>Samedi, de 11h \u00e0 4h du matin <span class=\"contentful-rich-text\" data-v-0c843bd4=\"\"><span class=\"text\" data-v-0c843bd4=\"\">(Derni\u00e8re entr\u00e9e \u00e0 3h15 du matin)<\/span><\/span><\/li>\n<li>Dimanche, de 11h \u00e0 2h du matin <span class=\"contentful-rich-text\" data-v-0c843bd4=\"\"><span class=\"text\" data-v-0c843bd4=\"\">(Derni\u00e8re entr\u00e9e \u00e0 1h45 du matin)<\/span><\/span><\/li>\n<\/ul>\n<p><strong>Tarifs :<\/strong> 22 SGD par personne sous forme de bon d&#8217;achat qui d\u00e9duira 22 SGD de votre facture au bar.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items no-masonry\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_1920-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_1920-scaled.jpg\" title=\"Vu de Singapour depuis le CE LA VI\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_1949-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_1949-scaled.jpg\" title=\"Vu de Singapour depuis le CE LA VI\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_2066-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_2066-scaled.jpg\" title=\"Vu de Singapour depuis le CE LA VI\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Singapour vue depuis le CE LA VI<\/em><\/p>\n<h4>Merlion Park<\/h4>\n<p>Embl\u00e8me de Singapour, le Merlion est repr\u00e9sent\u00e9 sur de nombreuses cartes postales et souvenirs.<\/p>\n<p>Il y a plusieurs statues du Merlion \u00e0 Singapour, mais la plus c\u00e9l\u00e8bre est situ\u00e9e au niveau de Marina Bay.<\/p>\n<p><strong>Horaires : <\/strong>24h\/24, 7j\/7<strong><br \/>\nTarifs<\/strong>\u00a0: Gratuit<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"75%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"2526\" width=\"2526\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd.jpg 2526w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd-300x300.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd-150x150.jpg 150w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd-1024x1024.jpg 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd-768x768.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd-1536x1536.jpg 1536w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd-2048x2048.jpg 2048w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd-100x100.jpg 100w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd-140x140.jpg 140w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd-500x500.jpg 500w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd-350x350.jpg 350w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd-1000x1000.jpg 1000w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/fdfc242ffd612382c212e04702e4d5f0fae144dd-800x800.jpg 800w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Merlion Park<\/em><\/p>\n<h4>Chinatown \/ Little India<\/h4>\n<p>Chinatown et Little India sont deux quartiers populaires de Singapour.<\/p>\n<p>N&#8217;h\u00e9sitez pas \u00e0 venir vous perdre dans le labyrinthe de rues \u00e9troites de Chinatown : vous y trouverez toute sorte de restaurants qui proposent des plats traditionnels comme le riz au poulet hainanais, les nouilles et le satay. Le quartier comporte aussi de nombreux magasins de souvenirs et boutiques.<\/p>\n<p>Un peu plus loin, vous trouverez Little India. Le quartier est connu pour ses restaurants indiens traditionnels, situ\u00e9s notamment le long de Serangoon Road et de Race Course Road. Les rues sont anim\u00e9es, quelle que soit l&#8217;heure du jour ou de la nuit.<\/p>\n<p><strong>Horaires : <\/strong>24h\/24, 7j\/7<strong><br \/>\nTarifs<\/strong>\u00a0: Gratuit<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items no-masonry\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_2973-1024x767-1-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_2973-1024x767-1.jpg\" title=\"Little India\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/17015-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/17015.jpg\" title=\"Chinatown\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/images.jpeg\" width=\"259\" height=\"194\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/images.jpeg\" title=\"Little India\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Chinatown et Little India<\/em><\/p>\n<h4>Sentosa<\/h4>\n<p>Sentosa est une petite \u00eele au sud de Singapour qui est d\u00e9di\u00e9 aux activit\u00e9s touristiques (parcs d&#8217;attractions, plages, resort h\u00f4telier&#8230;)<\/p>\n<p>Il est interdit de passer la nuit sur l&#8217;\u00eele sauf si l&#8217;on r\u00e9side \u00e0 Sentosa Cove ou dans l&#8217;un des resorts.<\/p>\n<p><strong>Horaires :<\/strong> De 9h \u00e0 22h (pour la plupart des attractions)<br \/>\n<strong>Tarifs :<\/strong> L&#8217;entr\u00e9e sur l&#8217;\u00eele \u00e0 pied est gratuite. 4 SGD en entrant avec le Sentosa Express (le retour est gratuit).<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items no-masonry\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160626_162524-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160626_162524-scaled.jpg\" title=\"Sentosa\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160626_161904-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160626_161904-scaled.jpg\" title=\"Sentosa\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160626_153153-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160626_153153-scaled.jpg\" title=\"Sentosa\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Les plages de Sentosa<\/em><\/p>\n<h4>Singapore Cable Car<\/h4>\n<p>Voici une fa\u00e7on originale de vous rendre \u00e0 Sentosa et \u00e0 MountFaber : le t\u00e9l\u00e9ph\u00e9rique de Singapour !<\/p>\n<p>Votre voyage ne durera que quelques minutes, mais vous verrez Singapour sous un angle diff\u00e9rent !<\/p>\n<p><strong>Horaires :<\/strong> De 8h45 \u00e0 21h30<br \/>\n<strong>Tarifs :<\/strong><\/p>\n<ul>\n<li>SkyPass (Touriste) : 35 SGD par adulte et 25 SGD par enfant<\/li>\n<li>SkyPass (R\u00e9sident) : 29.50 SGD par adulte et 21 SGD par enfant<\/li>\n<li>Ligne MountFaber (Touriste) : 33 SGD par adulte et 22 SGD par enfant<\/li>\n<li>Ligne MountFaber (R\u00e9sident) : 28 SGD par adulte et 18.50 SGD par enfant<\/li>\n<li>Ligne Sentosa (Touriste) : 15 SGD par adulte et 10 SGD par enfant<\/li>\n<li>Ligne Sentosa (R\u00e9sident) : 12.50 SGD par adulte et 8.50 SGD par enfant<\/li>\n<\/ul>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"75%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1920\" width=\"2560\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_5394-scaled.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_5394-scaled.jpg 2560w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_5394-300x225.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_5394-1024x768.jpg 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_5394-768x576.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_5394-1536x1152.jpg 1536w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_5394-2048x1536.jpg 2048w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Singapore Cable Car<\/em><\/p>\n<h4>Universal Studio<\/h4>\n<p>L&#8217;\u00eele de Sentosa accueille depuis mars 2010 le parc d&#8217;attractions Universal Studio. Il est compos\u00e9 de 7 zones \u00e0 th\u00e8mes et de 28 attractions sur diff\u00e9rents th\u00e8mes (Jurassic Park, Battlestar Galactica, Madagascar, Shrek, le retour de la momie&#8230;)<\/p>\n<p><strong>Horaires :<\/strong> De 10h \u00e0 18h<br \/>\n<strong>Tarifs :<\/strong><\/p>\n<ul>\n<li>Adulte (13-59 ans) : 81 SGD pour une journ\u00e9e<\/li>\n<li>Enfants (4-12 ans) : 61 SGD pour une journ\u00e9e<\/li>\n<li>Senior (&gt; 60 ans) : 43 SGD pour une journ\u00e9e<\/li>\n<\/ul>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"75%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1920\" width=\"2560\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160717_190221-scaled.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160717_190221-scaled.jpg 2560w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160717_190221-300x225.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160717_190221-1024x768.jpg 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160717_190221-768x576.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160717_190221-1536x1152.jpg 1536w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160717_190221-2048x1536.jpg 2048w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Universal Studio Singapour<\/em><\/p>\n<h4>Changi Airport<\/h4>\n<p>L&#8217;a\u00e9roport de Singapour a \u00e9t\u00e9 \u00e9lu plusieurs ann\u00e9es cons\u00e9cutives comme \u00e9tant le meilleur a\u00e9roport du monde, et pour l&#8217;avoir fr\u00e9quent\u00e9 \u00e0 de tr\u00e8s nombreuses reprises, je suis plut\u00f4t d&#8217;accord !<\/p>\n<p>Tout d&#8217;abord, vous pouvez d\u00e9poser vos bagages en soute \u00e0 n&#8217;importe quelle heure du jour et de la nuit : pas besoin d&#8217;attendre l&#8217;ouverture du guichet de la compagnie a\u00e9rienne. Pour cela, il vous suffit de vous rendre au service &#8220;Early-Checkin&#8221; du Jewel.<\/p>\n<p>Le Jewel, c&#8217;est un immense centre commercial qui est int\u00e9gr\u00e9 \u00e0 l&#8217;a\u00e9roport de Changi et qui a ouvert le 17 avril 2019. Le Jewel accueille de nombreux magasins, restaurants, et m\u00eame une \u00e9norme cascade nomm\u00e9e &#8220;The Rain Vortex&#8221;.<\/p>\n<p>\u00c0 l&#8217;int\u00e9rieur de la zone de transit, vous pouvez passer d&#8217;un terminal \u00e0 l&#8217;autre gr\u00e2ce \u00e0 un m\u00e9tro-navette : ainsi, m\u00eame si votre vol est au terminal 3, vous pourrez vous rendre \u00e0 la piscine (avec jacuzzi!) de l&#8217;a\u00e9roport (Terminal 1), au Cin\u00e9ma (Terminal 2 et 3) ou encore boire un cocktail gratuit dans l&#8217;une des boutiques du terminal 1.<\/p>\n<p>La piscine est ouverte tous les jours de 6h \u00e0 minuit. L&#8217;entr\u00e9e co\u00fbte 17 SGD par personne : vous aurez aussi acc\u00e8s aux douches et l&#8217;on vous pr\u00eatera une serviette de bain.<\/p>\n<p>Les cin\u00e9mas sont ouverts 24h\/24 7j\/7 et sont enti\u00e8rement gratuit.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items no-masonry\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/HSBC-Rain-Vortex-at-Jewel-Changi-Airport-1920x1440-1-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/HSBC-Rain-Vortex-at-Jewel-Changi-Airport-1920x1440-1.jpg\" title=\"Jewel\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160906_200626-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160906_200626-scaled.jpg\" title=\"Piscine \u00e0 l'a\u00e9roport de Changi\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4  element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/061de05d8be1965442716c713a3aada0-600x400.jpg\" width=\"600\" height=\"400\" alt=\"\" title=\"\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/061de05d8be1965442716c713a3aada0.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>L&#8217;a\u00e9roport de Changi \u00e0 Singapour<\/em><\/p>\n<h2>V &#8211; Les restaurants<\/h2>\n<p>\u00c0 Singapour, le plat national est le &#8220;Chicken Rice&#8221; : c&#8217;est un plat tr\u00e8s simple, qui comme son nom l&#8217;indique, est compos\u00e9 de riz et de poulet.<\/p>\n<p>Heureusement la population de Singapour vient des quatre coins de la plan\u00e8te et il tr\u00e8s facile de trouver tout type de cuisine.<\/p>\n<p>Voici une liste de quelques restaurants que je vous recommande \u00e0 Singapour :<\/p>\n<p><strong><span style=\"text-decoration: underline;\">Lau Pa Sat<\/span><\/strong><\/p>\n<p>Vous \u00eates de passage \u00e0 Singapour et vous souhaitez avoir un aper\u00e7u de la cuisine locale ? Alors rendez-vous \u00e0 Lau Pa Sat pour y commander un &#8220;Chicken Rice&#8221; !<\/p>\n<p>Lau Pa Sat est un &#8220;food court&#8221; : cela signifie que chacun peut commander des plats diff\u00e9rents aupr\u00e8s des petits stands pour ensuite les manger sur des tables communes.<\/p>\n<p><strong>Type : <\/strong>Food Court<strong><br \/>\nPrix :<\/strong>\u00a0$<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Din Tai Fung<\/strong><\/span><\/p>\n<p>Din Tai Fung est une cha\u00eene de restaurant ta\u00efwanaise : leur sp\u00e9cialit\u00e9 ? Les Dim Sum !<\/p>\n<p>Il y a tr\u00e8s souvent beaucoup d&#8217;attente donc n&#8217;h\u00e9siter pas \u00e0 arriver un peu en avance.<\/p>\n<p><strong>Type : <\/strong>Dim Sum<strong><br \/>\nPrix :<\/strong> $$$<br \/>\n<strong>Site internet :<\/strong> <a href=\"https:\/\/dintaifung.com.sg\/\">https:\/\/dintaifung.com.sg\/<\/a><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Gyu-Kaku<\/strong><\/span><\/p>\n<p>Gyu-Kaku est une cha\u00eene de restaurant sp\u00e9cialis\u00e9 dans le barbecue japonais. Les produits sont de tr\u00e8s bonne qualit\u00e9 : vous pouvez commander \u00e0 la carte ou en formule illimit\u00e9e.<\/p>\n<p><strong>Type : <\/strong>Barbecue Japonnais<strong><br \/>\nPrix :<\/strong> $$$<br \/>\n<strong>Site internet :<\/strong> <a href=\"https:\/\/www.gyu-kaku.com\/\">https:\/\/www.gyu-kaku.com\/<\/a><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>So France<\/strong><\/span><\/p>\n<p>Vous vivez \u00e0 Singapour et la cuisine fran\u00e7aise vous manque ? So France est un &#8220;bistro-\u00e9picerie&#8221; sp\u00e9cialis\u00e9 dans la cuisine du Sud Ouest.<\/p>\n<p>Les produits sont de tr\u00e8s bonne qualit\u00e9 et les prix sont tr\u00e8s raisonnables.<\/p>\n<p><strong>Type :<\/strong> Cuisine fran\u00e7aise (Sud-Ouest)<br \/>\n<strong>Prix :<\/strong> $$<br \/>\n<strong>Site internet :<\/strong> <a href=\"https:\/\/www.so-france.sg\/\">https:\/\/www.so-france.sg\/<\/a><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Pistachio grill<\/strong><\/span><\/p>\n<p>Pistachio grill est un restaurant sp\u00e9cialis\u00e9 dans la cuisine m\u00e9dit\u00e9ranenne et du moyen-orient.<\/p>\n<p><strong>Type :<\/strong> Cuisine M\u00e9dit\u00e9ran\u00e9nne<br \/>\n<strong>Prix :<\/strong> $$<br \/>\n<strong>Site internet :<\/strong> <a href=\"https:\/\/www.pistachiogrill.com\/\">https:\/\/www.pistachiogrill.com\/<\/a><\/p>\n<p><strong><span style=\"text-decoration: underline;\">Keisuke<\/span><\/strong><\/p>\n<p>Keisuke est la plus grosse cha\u00eene de restaurant de ramen de Singapour.<\/p>\n<p><strong>Type :<\/strong> Ramen<br \/>\n<strong>Prix :<\/strong> $<br \/>\n<strong>Site internet :<\/strong> <a href=\"https:\/\/www.keisuke.sg\/\">https:\/\/www.keisuke.sg\/<\/a><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Swee Chong<\/strong><\/span><\/p>\n<p>Pr\u00e9sent \u00e0 Singapour depuis 1962, Swee Chong est une institution des dim sum \u00e0 Singapour.<\/p>\n<p><strong>Type :<\/strong> Dim Sum<br \/>\n<strong>Prix :<\/strong> $$$<br \/>\n<strong>Site internet :<\/strong> <a href=\"https:\/\/www.sweechoon.com\/\">https:\/\/www.sweechoon.com\/<\/a><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Meat n Chill<\/strong><\/span><\/p>\n<p>Situ\u00e9 sur Bukit Timah Road, Meat n Chill est un restaurant pour les amateurs de viande.<\/p>\n<p><strong>Type :<\/strong> Steak<br \/>\n<strong>Prix :<\/strong> $$<br \/>\n<strong>Site internet :<\/strong> <a href=\"https:\/\/meatnchill.com\/\">https:\/\/meatnchill.com\/<\/a><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Jumbo Seafood<\/strong><\/span><\/p>\n<p>Jumbo Seafood est une cha\u00eene de restaurant de fruit de mer originaire de Singapour.<\/p>\n<p><strong>Type :<\/strong> Fruit de mer<br \/>\n<strong>Prix :<\/strong> $$$<br \/>\n<strong>Site internet :<\/strong> <a href=\"https:\/\/www.jumboseafood.com.sg\/\">https:\/\/www.jumboseafood.com.sg\/<\/a><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Sankranti<\/strong><\/span><\/p>\n<p>Sankranti est une cha\u00eene de restaurant qui sert de la cuisine indienne.<\/p>\n<p><strong>Type :<\/strong> Cuisine indienne<br \/>\n<strong>Prix :<\/strong> $$<br \/>\n<strong>Site internet :<\/strong> <a href=\"http:\/\/sankrantihotels.com\/\">http:\/\/sankrantihotels.com\/<\/a><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Blu Kuzina<\/strong><\/span><\/p>\n<p>Blu Kuzina est un tr\u00e8s bon restaurant grec \u00e0 Singapour.<\/p>\n<p><strong>Type :<\/strong> Grec<br \/>\n<strong>Prix :<\/strong> $$<br \/>\n<strong>Site internet :<\/strong> <a href=\"https:\/\/blukouzina.com\/SG\/\">https:\/\/blukouzina.com\/SG\/<\/a><\/p>\n<p><strong><span style=\"text-decoration: underline;\">Yoogane<\/span><\/strong><\/p>\n<p>Yoogane est un restaurant qui sert de la cuisine cor\u00e9enne.<\/p>\n<p><strong>Type :<\/strong> Cuisine cor\u00e9enne<br \/>\n<strong>Prix :<\/strong> $$<br \/>\n<strong>Site internet :<\/strong> <a href=\"https:\/\/www.facebook.com\/yoogane.singapore\">https:\/\/www.facebook.com\/yoogane.singapore<\/a><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Seorae<\/strong><\/span><\/p>\n<p>L&#8217;un des meilleurs restaurants de barbecue cor\u00e9en \u00e0 Singapour.<\/p>\n<p><strong>Type :<\/strong> Barbecue cor\u00e9en<br \/>\n<strong>Prix : <\/strong>$$<strong><br \/>\nSite internet : <\/strong><a href=\"https:\/\/www.seorae.com.sg\/\">https:\/\/www.seorae.com.sg\/<\/a><strong><br \/>\n<\/strong><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Hai Do Lao<\/strong><\/span><\/p>\n<p>Originaire de Chine, cette cha\u00eene de restaurant de Hot Pot est arriv\u00e9e \u00e0 Singapour en 2012.<\/p>\n<p>Il y a toujours \u00e9norm\u00e9ment d&#8217;attente dans leurs restaurants donc n&#8217;h\u00e9sitez pas \u00e0 arriver en avance.<\/p>\n<p><strong>Type :<\/strong> Hot Pot<br \/>\n<strong>Prix :<\/strong> $$$<br \/>\n<strong>Site internet :<\/strong> <a href=\"https:\/\/www.haidilao.com\/sg\/\">https:\/\/www.haidilao.com\/sg\/<\/a><\/p>\n<p><strong><span style=\"text-decoration: underline;\">Jai Thai<\/span><\/strong><\/p>\n<p>Jai Thai est une petite cha\u00eene de restaurant servant de la cuisine tha\u00eflandaise.<\/p>\n<p><strong>Type :<\/strong> Cuisine tha\u00eflandaise<br \/>\n<strong>Prix :<\/strong> $$<br \/>\n<strong>Site internet :<\/strong> <a href=\"https:\/\/www.jai-thai.com\/\">https:\/\/www.jai-thai.com\/<\/a><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>VI &#8211; Les transports<\/h2>\n<h4><span style=\"text-decoration: underline;\"><strong>La voiture personnelle<\/strong><\/span><\/h4>\n<p>\u00c0 Singapour, avoir une voiture personnelle n&#8217;est pas indispensable : toute l&#8217;\u00eele (ou presque) est accessible en transport en commun ou en taxi.<\/p>\n<p>Il s&#8217;agit de la ville o\u00f9 l\u2019achat et la location d\u2019une voiture co\u00fbtent le plus cher au monde. En effet, le gouvernement cherche \u00e0 r\u00e9duire le nombre de v\u00e9hicules en circulation sur l&#8217;\u00eele.<\/p>\n<p>Pour cela, le gouvernement a instaur\u00e9 de nombreuses taxes : par exemple, un petit SUV peut co\u00fbter jusqu&#8217;\u00e0 100 000 SGD (environ 65 000 euros).<\/p>\n<p>En plus du prix du v\u00e9hicule et des taxes, vous devrez obtenir un <em>Certificate of Entitlement<\/em> (COE) : il s&#8217;agit d&#8217;une autorisation de circulation pour votre voiture valable pendant 5 ans (elle est valable 10 ans pour les Singapouriens). Son co\u00fbt ? Jusqu&#8217;\u00e0 37 000 SGD (soit 32 000 euros).<\/p>\n<h4><span style=\"text-decoration: underline;\">Le m\u00e9tro \/ le bus<\/span><\/h4>\n<p>Le r\u00e9seau de m\u00e9tro (MRT) de Singapour est tr\u00e8s d\u00e9velopp\u00e9 : il est possible de traverser l&#8217;\u00eele en long et en large gr\u00e2ce au m\u00e9tro.<\/p>\n<p>\u00c0 Singapour, il n&#8217;existe pas d&#8217;abonnement mensuel pour les transports en commun : vous devez mettre de l&#8217;argent sur votre carte de transport et le montant du trajet sera d\u00e9duit \u00e0 chaque passage.<\/p>\n<p>Les prix sont tr\u00e8s abordables : pour moins de 2 SGD (environ 1.30 EUR) vous pouvez traverser Singapour du nord au Sud.<\/p>\n<p>Tout comme le r\u00e9seau de m\u00e9tro, le r\u00e9seau de bus est tr\u00e8s d\u00e9velopp\u00e9 \u00e0 Singapour.<\/p>\n<h4><span style=\"text-decoration: underline;\"><strong>Les taxis \/ Les VTC<\/strong><\/span><\/h4>\n<p>\u00e0 Singapour, les taxis et les VTC sont assez abordables. Ils acceptent le paiement par carte bancaire et en cash.<\/p>\n<p>En cas de pluie, il vous sera plus difficile de trouver un taxi dans la rue&#8230; Vous aurez plus de chance sur les applis VTC mais le prix sera plus cher.<\/p>\n<p>En 2018, Uber a quitt\u00e9 Singapour au profit de Grab.<\/p>\n<h4><span style=\"text-decoration: underline;\">Le v\u00e9lo<\/span><\/h4>\n<p>Singapour n&#8217;est clairement pas une ville adapt\u00e9e au v\u00e9lo : il y a tr\u00e8s peu de pistes cyclables.<\/p>\n<p>Il y a quelques ann\u00e9es, de nombreux v\u00e9los en libre-service (sans bornes) \u00e9taient disponibles : ils ont pour la plupart disparu suite \u00e0 un changement de r\u00e9glementation.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>VII &#8211; Le climat<\/h2>\n<p>Situ\u00e9 proche de l&#8217;\u00e9quateur, le climat de Singapour est chaud, humide et pluvieux toute l&#8217;ann\u00e9e.<\/p>\n<p>Les temp\u00e9ratures sont assez uniformes tout au long de l&#8217;ann\u00e9e :<\/p>\n<table style=\"border-collapse: collapse; width: 100%; height: 96px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 19.7973%; height: 24px; text-align: center;\"><strong>Mois<\/strong><\/td>\n<td style=\"width: 1.68919%; height: 24px; text-align: center;\"><strong>Jan<\/strong><\/td>\n<td style=\"width: 5.10135%; height: 24px; text-align: center;\"><strong>F\u00e9v<\/strong><\/td>\n<td style=\"width: 2.22968%; height: 24px; text-align: center;\"><strong>Mar<\/strong><\/td>\n<td style=\"width: 8.31081%; height: 24px; text-align: center;\"><strong>Avr<\/strong><\/td>\n<td style=\"width: 7.80401%; height: 24px; text-align: center;\"><strong>Mai<\/strong><\/td>\n<td style=\"width: 9.32436%; height: 24px; text-align: center;\"><strong>Juin<\/strong><\/td>\n<td style=\"width: 10.8446%; height: 24px; text-align: center;\"><strong>Jui<\/strong><\/td>\n<td style=\"width: 10.3378%; height: 24px; text-align: center;\"><strong>Ao\u00fb<\/strong><\/td>\n<td style=\"width: 9.72972%; height: 24px; text-align: center;\"><strong>Sep<\/strong><\/td>\n<td style=\"width: 6.99328%; text-align: center; height: 24px;\"><strong>Oct<\/strong><\/td>\n<td style=\"width: 6.19932%; text-align: center; height: 24px;\"><strong>Nov<\/strong><\/td>\n<td style=\"width: 0.625%; text-align: center; height: 24px;\"><strong>D\u00e9c<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 19.7973%; height: 48px; text-align: center;\"><strong>Min (\u00b0C)<\/strong><\/td>\n<td style=\"width: 1.68919%; height: 48px; text-align: center;\">23<\/td>\n<td style=\"width: 5.10135%; height: 48px; text-align: center;\">24<\/td>\n<td style=\"width: 2.22968%; height: 48px; text-align: center;\">24<\/td>\n<td style=\"width: 8.31081%; height: 48px; text-align: center;\">24<\/td>\n<td style=\"width: 7.80401%; height: 48px; text-align: center;\">25<\/td>\n<td style=\"width: 9.32436%; height: 48px; text-align: center;\">25<\/td>\n<td style=\"width: 10.8446%; height: 48px; text-align: center;\">24<\/td>\n<td style=\"width: 10.3378%; height: 48px; text-align: center;\">24<\/td>\n<td style=\"width: 9.72972%; height: 48px; text-align: center;\">24<\/td>\n<td style=\"width: 6.99328%; text-align: center; height: 48px;\">24<\/td>\n<td style=\"width: 6.19932%; text-align: center; height: 48px;\">24<\/td>\n<td style=\"width: 0.625%; text-align: center; height: 48px;\">23<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 19.7973%; height: 24px; text-align: center;\"><strong>Max (\u00b0C)<\/strong><\/td>\n<td style=\"width: 1.68919%; height: 24px; text-align: center;\">30<\/td>\n<td style=\"width: 5.10135%; height: 24px; text-align: center;\">31<\/td>\n<td style=\"width: 2.22968%; height: 24px; text-align: center;\">31<\/td>\n<td style=\"width: 8.31081%; height: 24px; text-align: center;\">32<\/td>\n<td style=\"width: 7.80401%; height: 24px; text-align: center;\">32<\/td>\n<td style=\"width: 9.32436%; height: 24px; text-align: center;\">31<\/td>\n<td style=\"width: 10.8446%; height: 24px; text-align: center;\">31<\/td>\n<td style=\"width: 10.3378%; height: 24px; text-align: center;\">31<\/td>\n<td style=\"width: 9.72972%; height: 24px; text-align: center;\">31<\/td>\n<td style=\"width: 6.99328%; text-align: center; height: 24px;\">31<\/td>\n<td style=\"width: 6.19932%; text-align: center; height: 24px;\">31<\/td>\n<td style=\"width: 0.625%; text-align: center; height: 24px;\">30<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>M\u00eame la nuit, la temp\u00e9rature ne descend jamais en dessous des 20\u00b0C.<\/p>\n<p>De novembre \u00e0 janvier, les pluies sont plus fr\u00e9quentes et durent plus longtemps, et se produisent g\u00e9n\u00e9ralement dans l&#8217;apr\u00e8s-midi ou dans la soir\u00e9e.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>VIII &#8211; Le co\u00fbt de la vie<\/h2>\n<p>C&#8217;est incontestable : Singapour est l&#8217;une des villes les plus ch\u00e8res au monde. Selon le site lecoutdelexpat.com, vivre \u00e0 Singapour co\u00fbte 109% plus cher qu&#8217;\u00e0 Paris !<\/p>\n<p>Certes, les salaires sont g\u00e9n\u00e9ralement plus \u00e9lev\u00e9s qu&#8217;en France, mais certains postes de d\u00e9pense le sont \u00e9galement :<\/p>\n<h3>Ce qui co\u00fbte plus cher \u00e0 Singapour :<\/h3>\n<h4>Les logements<\/h4>\n<p>Comme je vous le disais dans la deuxi\u00e8me partie de cet article, le prix des loyers \u00e0 Singapour est tr\u00e8s \u00e9lev\u00e9.<\/p>\n<p>Pour r\u00e9duire ce co\u00fbt, les \u00e9tudiants et les jeunes actifs se mettent tr\u00e8s souvent en colocation : cela permet aussi d&#8217;avoir un logement plus grand \/ mieux \u00e9quip\u00e9.<\/p>\n<h4>Les voitures<\/h4>\n<p>Poss\u00e9der une voiture \u00e0 Singapour est hors de prix : entre le prix d&#8217;achat, les assurances, les taxes, les p\u00e9ages, les parkings&#8230;<\/p>\n<p>Par exemple, selon MoneyMart, une Toyota Corolla Altis neuve co\u00fbte plus de 67 000 euros (105 988 SGD) ! Si une voiture neuve co\u00fbte si cher, c&#8217;est d&#8217;abord une volont\u00e9 politique : le gouvernement souhaite limiter le nombre de voitures en circulation sur l&#8217;\u00eele.<\/p>\n<p>Heureusement, la voiture n&#8217;est clairement pas indispensable \u00e0 Singapour car le r\u00e9seau de transport en commun est tr\u00e8s d\u00e9velopp\u00e9.<\/p>\n<h4>L&#8217;alcool<\/h4>\n<p>Que cela soit au supermarch\u00e9 ou au bar, l&#8217;alcool est beaucoup plus cher \u00e0 Singapour. L\u00e0 encore, il s&#8217;agit d&#8217;une volont\u00e9 politique : pas question pour le gouvernement que la population abuse de l&#8217;alcool.<\/p>\n<p>La majorit\u00e9 du prix correspond donc principalement \u00e0 une taxe gouvernementale.<\/p>\n<h4>Les cigarettes \/ le tabac<\/h4>\n<p>Tout comme l\u2019alcool, les cigarettes et le tabac sont tr\u00e8s lourdement tax\u00e9s \u00e0 Singapour afin d&#8217;\u00e9viter que la population n&#8217;en consomme.<\/p>\n<p>Par exemple, le paquet de Malboro rouge co\u00fbte pr\u00e8s de 14 SGD.<\/p>\n<h4>Les produits de luxe<\/h4>\n<p>Les produits des marques de luxe (Louis Vuitton, Prada&#8230;) sont aussi g\u00e9n\u00e9ralement plus chers \u00e0 Singapour qu&#8217;en France.<\/p>\n<p>M\u00eame le caf\u00e9 Nespresso co\u00fbte plus cher : compter environ 2 fois le prix pour la machine ainsi que pour les capsules !<\/p>\n<h4>La t\u00e9l\u00e9phonie mobile<\/h4>\n<p>C&#8217;est un domaine o\u00f9 les prix ont beaucoup baiss\u00e9 depuis mon arriv\u00e9 \u00e0 Singapour, mais on est encore loin des offres fran\u00e7aises !<\/p>\n<p>\u00c0 l&#8217;heure actuelle, l&#8217;offre la plus int\u00e9ressante est propos\u00e9e par Circle.Life (20 GO, 100 minutes, 25 SMS pour 18 SGD\/mois ou 100 GO, 100 minutes, 25 SMS pour 38 SGD \/ mois) mais les prix risquent encore d&#8217;\u00eatre revu \u00e0 la baisse gr\u00e2ce \u00e0 l&#8217;arriv\u00e9e d&#8217;un nouvel op\u00e9rateur en provenance d&#8217;Australie : TPG Mobile (leur abonnement \u00e9tait m\u00eame gratuit pendant la b\u00eata).<\/p>\n<p>Certains postes de d\u00e9penses sont en revanche moins chers qu&#8217;en France :<\/p>\n<h3>Ce qui co\u00fbte moins cher \u00e0 Singapour :<\/h3>\n<h4>Se nourrir<\/h4>\n<p>Se nourrir \u00e0 Singapour ne co\u00fbte pas tr\u00e8s cher \u00e0 une condition : d&#8217;accepter de manger local ! Si vous ne pouvez pas vous passer de vin ou de fromage \u00e0 tous les repas, alors votre budget alimentation sera sans doute beaucoup plus cons\u00e9quent.<\/p>\n<p>En plus des restaurants classiques, vous trouverez \u00e0 Singapour des &#8220;Food Court&#8221; : ce sont des cafeterias avec plein de petits stands diff\u00e9rents o\u00f9 chacun peut commander ce qu&#8217;il aime et se retrouver ensuite sur la m\u00eame table pour d\u00e9jeuner ou d\u00eener. Les food courts sont la mani\u00e8re la plus \u00e9conomique de se nourrir \u00e0 Singapour, mais certainement pas la plus saine ni la plus gastronomique.<\/p>\n<h4>Se d\u00e9placer<\/h4>\n<p>Si l&#8217;on retire la voiture de l&#8217;\u00e9quation, se d\u00e9placer \u00e0 Singapour est tr\u00e8s abordable ! Tout d&#8217;abord le r\u00e9seau de transport en commun est tr\u00e8s d\u00e9velopp\u00e9 et vous pouvez vous rendre d&#8217;un bout \u00e0 l&#8217;autre de la ville en m\u00e9tro ou en bus pour quelques Singapour dollars. Il n&#8217;existe pas d&#8217;abonnement mensuel ou annuel pour les transports (sauf peut-\u00eatre pour les \u00e9tudiants et les seniors), mais vous pouvez acheter une carte de transport pr\u00e9pay\u00e9 que vous pourrez recharger \u00e0 volont\u00e9.<\/p>\n<p>Depuis quelque temps, il est m\u00eame possible de payer le trajet directement avec votre carte bancaire sans contact lors du passage du tourniquet ou lors de votre mont\u00e9e dans le bus.<\/p>\n<p>Les taxis et les applis de VTC sont \u00e9galement moins chers qu&#8217;en France : Notez toutefois qu&#8217;Uber n&#8217;est plus disponible \u00e0 Singapour car ils ont \u00e9t\u00e9 rachet\u00e9s par Grab, une autre appli de VTC tr\u00e8s pr\u00e9sente en Asie.<\/p>\n<p>En plus des postes de d\u00e9pense classiques, n&#8217;oubliez pas que vous \u00eates \u00e0 l&#8217;\u00e9tranger et que vous aurez d&#8217;autres d\u00e9penses suppl\u00e9mentaires :<\/p>\n<ul>\n<li>des billets d&#8217;avion Paris &#8211; Singapour pour aller voir votre famille \/ vos amis<\/li>\n<li>une assurance maladie et mutuelle<\/li>\n<li>le co\u00fbt de l&#8217;\u00e9ducation de vos enfants<\/li>\n<\/ul>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>IX &#8211; Les imp\u00f4ts<\/h2>\n<p>\u00c0 Singapour, les salaires sont nettement plus \u00e9lev\u00e9s : environ 10 \u00e0 30% de plus qu&#8217;en France selon votre industrie, notamment \u00e0 cause du co\u00fbt de la vie. En revanche, ce n&#8217;est pas le cas pour les m\u00e9tiers peu qualifi\u00e9s qui ne sont de toute mani\u00e8re pas accessibles pour les \u00e9trangers.<\/p>\n<p>Il n&#8217;y a pas de cotisations sociales : c&#8217;est-\u00e0-dire que votre salaire brut est \u00e9gal \u00e0 votre salaire net. En contrepartie, il n&#8217;y a pas de ch\u00f4mage, d&#8217;assurance maladie et de cotisation retraite : chaque salari\u00e9 peut d\u00e9cider (ou non) de souscrire \u00e0 des assurances priv\u00e9es.<\/p>\n<p>Comme en France, l&#8217;imp\u00f4t sur le revenu est progressif. En revanche, le taux d&#8217;imposition est beaucoup plus faible \u00e0 Singapour qu&#8217;en France. Voici un tableau que je vous donne \u00e0 titre indicatif (cela peut bien s\u00fbr \u00e9voluer d&#8217;une ann\u00e9e \u00e0 l&#8217;autre, pour plus d&#8217;informations, <a href=\"https:\/\/www.iras.gov.sg\/\">consulter le site de l&#8217;IRAS<\/a>) :<\/p>\n<table style=\"border-collapse: collapse; width: 100%; height: 388px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 18.581%; text-align: center; height: 24px;\"><strong>Votre salaire est de&#8230;<\/strong><\/td>\n<td style=\"width: 28.3447%; text-align: center; height: 24px;\"><strong>Palier<\/strong><\/td>\n<td style=\"width: 19.6621%; text-align: center; height: 24px;\"><strong>Taux d&#8217;imposition<\/strong><\/td>\n<td style=\"width: 13.4122%; text-align: center; height: 24px;\"><strong>Montant \u00e0 payer<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 18.581%; height: 48px;\">Moins de 30 000 SGD par an<\/td>\n<td style=\"width: 28.3447%; height: 48px;\">\n<table style=\"height: 34px; width: 100%; border-collapse: collapse; border-style: hidden; border-color: #ffffff;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; height: 10px; text-align: left; border-style: hidden; background-color: #ffffff;\">Premier 20 000 SGD<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; height: 24px; text-align: left; border-style: hidden; background-color: #ffffff;\">Les 10 000 SGD suivants<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 19.6621%; height: 48px;\">\n<table style=\"width: 100%; border-collapse: collapse; border-style: hidden;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; background-color: #ffffff; border-style: hidden; text-align: center;\">0.00 %<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; text-align: center;\">2.00 %<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 13.4122%; height: 48px;\">\n<table style=\"width: 100%; border-collapse: collapse; border-style: hidden; height: 48px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; height: 24px; background-color: #ffffff; border-style: hidden; text-align: center;\">0<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; height: 24px; text-align: center;\">200<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 18.581%; height: 48px; background-color: #ffffff;\">Entre 30 000<br \/>\net<br \/>\n40 000 SGD par an<\/td>\n<td style=\"width: 28.3447%; height: 48px; background-color: #ffffff; text-align: center;\">\n<table style=\"border-collapse: collapse; width: 100%; height: 48px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; height: 24px; border-style: hidden; background-color: #ffffff; text-align: left;\">Premier 30 000 SGD<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; height: 24px; border-style: hidden; text-align: left;\">Les 10 000 SGD suivants<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 19.6621%; height: 48px; background-color: #ffffff;\">\n<table style=\"height: 48px; width: 100%; border-collapse: collapse; border-style: hidden; background-color: #ffffff;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; height: 24px; text-align: center;\">&#8211;<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; height: 24px; border-style: hidden; text-align: center;\">3.50 %<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 13.4122%; height: 48px; background-color: #ffffff;\">\n<table style=\"border-collapse: collapse; width: 100%; height: 48px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; height: 24px; border-style: hidden; background-color: #ffffff; text-align: center;\">200<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; height: 24px; border-style: hidden; text-align: center;\">350<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 18.581%; height: 48px;\">Entre 40 000<br \/>\net<br \/>\n80 000 SGD par an<\/td>\n<td style=\"width: 28.3447%; height: 48px; text-align: center;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left;\">Premier 40 000 SGD<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left;\">Les 40 000 SGD suivants<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 19.6621%; height: 48px;\">\n<table style=\"border-collapse: collapse; width: 100%; height: 48px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center; height: 24px;\">&#8211;<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">7.00 %<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 13.4122%; height: 48px;\">\n<table style=\"border-collapse: collapse; width: 100%; height: 48px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">500<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">2 800<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 18.581%; height: 24px; background-color: #ffffff;\">Entre 80 000<br \/>\net<br \/>\n120 000 SGD par an<\/td>\n<td style=\"width: 28.3447%; height: 24px; background-color: #ffffff; text-align: center;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left;\">Premier 80 000 SGD<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left;\">Les 40 000 SGD suivants<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 19.6621%; height: 24px; background-color: #ffffff;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">11.50 %<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 13.4122%; height: 24px; background-color: #ffffff;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">3 350<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">4 600<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 18.581%; height: 24px;\">Entre 120 000<br \/>\net<br \/>\n160 000 SGD par an<\/td>\n<td style=\"width: 28.3447%; height: 24px; text-align: center;\">\n<table style=\"width: 100%; text-align: left; border-style: hidden; background-color: #ffffff;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left;\">Premier 120 000 SGD<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left;\">Les 40 000 SGD suivants<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 19.6621%; height: 24px;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">15.00 %<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 13.4122%; height: 24px;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">7 950<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">6 000<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 18.581%; height: 24px; background-color: #ffffff;\">Entre 160 000<br \/>\net<br \/>\n200 000 SGD par an<\/td>\n<td style=\"width: 28.3447%; height: 24px; background-color: #ffffff; text-align: center;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left;\">Premier 160 000 SGD<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left;\">Les 40 000 SGD suivants<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 19.6621%; height: 24px; background-color: #ffffff;\">\n<table style=\"border-collapse: collapse; width: 100%; height: 48px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">&#8211;<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">18.00%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 13.4122%; height: 24px; background-color: #ffffff;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">13 950<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">7 200<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 18.581%; height: 24px;\">Entre 200 000<br \/>\net<br \/>\n240 000 SGD par an<\/td>\n<td style=\"width: 28.3447%; height: 24px; text-align: center;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left;\">Premier 200 000 SGD<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left;\">Les 40 000 SGD suivants<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 19.6621%; height: 24px;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">19.00%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 13.4122%; height: 24px;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">21 150<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">7 600<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 18.581%; height: 24px; background-color: #ffffff;\">Entre 240 000<br \/>\net<br \/>\n280 000 SGD par an<\/td>\n<td style=\"width: 28.3447%; height: 24px; background-color: #ffffff; text-align: center;\">\n<table style=\"border-collapse: collapse; width: 100%; height: 48px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left; height: 24px;\">Premier 240 000 SGD<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left; height: 24px;\">Les 40 000 SGD suivants<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 19.6621%; height: 24px; background-color: #ffffff;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">19.50%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 13.4122%; height: 24px; background-color: #ffffff;\">\n<table style=\"border-collapse: collapse; width: 100%; height: 48px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">28 750<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">7 800<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td style=\"width: 18.581%; height: 48px;\">Entre 280 000<br \/>\net<br \/>\n320 000 SGD par an<\/td>\n<td style=\"width: 28.3447%; text-align: center; height: 48px;\">\n<table style=\"border-collapse: collapse; width: 100%; height: 48px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left; height: 24px;\">Premier 280 000 SGD<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left;\">Les 40 000 SGD suivants<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 19.6621%; height: 48px;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">20.00%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 13.4122%; height: 48px;\">\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">36 550<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center;\">8 000<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 18.581%; height: 52px; background-color: #ffffff;\">Plus de 320 000 SGD par an<\/td>\n<td style=\"width: 28.3447%; text-align: center; height: 52px; background-color: #ffffff;\">\n<table style=\"height: 48px; width: 100%; border-collapse: collapse; background-color: #ffffff;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; height: 24px; text-align: left;\">Premier 320 000 SGD<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: left; height: 24px;\">Au-dessus de 320 000 SGD<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 19.6621%; height: 52px; background-color: #ffffff;\">\n<table style=\"height: 48px; width: 100%; border-collapse: collapse; background-color: #ffffff;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center; height: 24px;\">&#8211;<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center; height: 24px;\">22.00 %<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<td style=\"width: 13.4122%; height: 52px; background-color: #ffffff;\">\n<table style=\"border-collapse: collapse; width: 100%; height: 48px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; text-align: center; height: 24px;\">44 550<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 100%; border-style: hidden; background-color: #ffffff; height: 24px;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>X &#8211; Les visas<\/h2>\n<h4><span style=\"text-decoration: underline;\"><strong>EN TANT QUE TOURISTE :<\/strong><\/span><\/h4>\n<p><span style=\"color: #339966;\"><strong>PAS BESOIN DE VISA<\/strong>, pour les Fran\u00e7ais qui souhaitent faire du tourisme pendant moins de 90 jours<\/span><\/p>\n<h4><span style=\"text-decoration: underline;\"><strong>POUR Y TRAVAILLER :<\/strong><\/span><\/h4>\n<p>\u00c0 Singapour, ce sont les entreprises qui doivent faire la demande de visa de travail pour leurs employ\u00e9s \u00e9trangers (\u00e0 deux exceptions pr\u00e8s : le WHP et le PEP).<\/p>\n<p>Cela signifie que si vous souhaitez obtenir un visa de travail classique, vous devrez d&#8217;abord trouver une entreprise qui accepte de vous engager car le visa de travail ne vous sera accord\u00e9 que pour cette entreprise :<\/p>\n<ul>\n<li>Si vous quittez l&#8217;entreprise (volontairement ou non), vous perdez votre visa.<\/li>\n<li>Si vous changez d&#8217;entreprise, votre nouvelle entreprise devra refaire la proc\u00e9dure de visa (avec le risque d&#8217;avoir un refus).<\/li>\n<\/ul>\n<p>La plupart des \u00e9trangers poss\u00e8dent l&#8217;un des visas suivants : EP, S Pass, DP, LTVP, WHP ou PEP.<\/p>\n<p>Certaines nationalit\u00e9s, par exemple les Indiens ou les Indon\u00e9siens, peuvent pr\u00e9tendre au Working Permit.<\/p>\n<p>Voyons ensemble en d\u00e9tail les diff\u00e9rents visas :<\/p>\n<h4><span style=\"text-decoration: underline;\"><strong>Employment Pass (EP)<\/strong><\/span><\/h4>\n<p>C&#8217;est LE visa que poss\u00e8dent la plupart des \u00e9trangers qualifi\u00e9s. Pour l&#8217;obtenir, il faut pouvoir justifier de &#8220;qualifications acceptables&#8221; : une notion fourre-tout qui permet au Ministry of Manpower d&#8217;accepter ou de refuser un dossier sans avoir \u00e0 motiver sa r\u00e9ponse.<\/p>\n<p>Le second crit\u00e8re d&#8217;obtention de l&#8217;EP est purement financier : votre salaire doit \u00eatre d&#8217;au moins 3 900 SGD.<\/p>\n<p>Si vous avez un niveau de formation Master et \/ ou une exp\u00e9rience professionnelle importante, vous pourrez sans aucun doute obtenir un EP assez facilement. Cependant, notez qu&#8217;il est souvent plus difficile d&#8217;obtenir un EP lorsque les \u00e9lections g\u00e9n\u00e9rales (GE) approchent.<\/p>\n<p>Un EP est valable pendant 2 ans, puis une fois renouvel\u00e9 il pourra \u00eatre valable jusqu&#8217;\u00e0 3 ans.<\/p>\n<p>Une personne ayant un EP peut obtenir des visas pour sa famille \u00e0 condition d&#8217;avoir un salaire sup\u00e9rieur \u00e0 6 000 SGD par mois :<\/p>\n<ul>\n<li>Un Dependant Pass pour les conjoints mari\u00e9s et les enfants de moins de 21 ans.<\/li>\n<li>Un Long Term Visit Pass pour les conjoints pacs\u00e9s et les concubins<\/li>\n<\/ul>\n<p>Attention : Si vous perdez votre EP, les personnes qui &#8220;d\u00e9pendent&#8221; de vous, perdront \u00e9galement leur visa !<\/p>\n<h4><span style=\"text-decoration: underline;\"><strong>S-Pass<\/strong><\/span><\/h4>\n<p>Le S-Pass, c&#8217;est une version &#8220;light&#8221; de l&#8217;EP : Si vous avez moins de qualifications et \/ou d&#8217;exp\u00e9rience, alors il y a de grandes chances que vous obtiendrez un S-Pass plut\u00f4t qu&#8217;un EP. Vous devez avoir un salaire d&#8217;au moins 2 000 SGD par mois.<\/p>\n<p>Une personne ayant un S-Pass peut obtenir un Dependant Pass pour son conjoint mari\u00e9 \u00e0 condition d&#8217;avoir un salaire sup\u00e9rieur \u00e0 2 800 SGD par mois.<\/p>\n<p>Le S-Pass sont soumis \u00e0 des quotas pour l&#8217;entreprise : les crit\u00e8res \u00e9voluent avec le temps, mais en g\u00e9n\u00e9ral ils suivent la formule suivante : &#8220;Pour X Singapouriens engag\u00e9s par l&#8217;entreprise, celle-ci peut engager Y \u00e9trangers avec un S-Pass&#8221;<\/p>\n<h4><span style=\"text-decoration: underline;\"><strong>Dependant Pass (DP)<\/strong><\/span><\/h4>\n<p>Un Dependant Pass c&#8217;est un visa de conjoint mari\u00e9 ou d&#8217;enfant de moins de 21 ans. Par d\u00e9finition, il est rattach\u00e9 \u00e0 un EP ou \u00e0 un S-Pass.<\/p>\n<p>Avec un Dependant Pass, vous pouvez travailler \u00e0 Singapour (sous certaines conditions) mais vous devrez obtenir une &#8220;Letter of consent&#8221; (si vous \u00eates rattach\u00e9 \u00e0 un EP) ou un &#8220;Work Permit&#8221; (si vous \u00eates rattach\u00e9 \u00e0 un S-Pass).<\/p>\n<h4><span style=\"text-decoration: underline;\"><strong>Long Term Visit Pass (LTVP)<\/strong><\/span><\/h4>\n<p>Le LTVP est un visa qui est rattach\u00e9 \u00e0 un EP ou \u00e0 un S-Pass. Il permet de faire venir certains membres de la famille de la personne qui poss\u00e8de l&#8217;EP : ses parents, son conjoint non mari\u00e9, ses beaux-enfants ou un enfant majeur handicap\u00e9.<\/p>\n<p>Ce visa ne vous permet pas en th\u00e9orie de travailler \u00e0 Singapour.<\/p>\n<h4><span style=\"text-decoration: underline;\"><strong>Working Holiday Pass (WHP)<\/strong><\/span><\/h4>\n<p>Le WHP est souvent une porte d&#8217;entr\u00e9e pour les jeunes qui souhaitent faire un stage \u00e0 Singapour ou y d\u00e9buter une carri\u00e8re : j&#8217;ai personnellement commenc\u00e9 avec un WHP.<\/p>\n<p>Ce visa vous donne le droit de rester et de travailler \u00e0 Singapour pendant 6 mois. Il n&#8217;est pas renouvelable et il ne permet pas d&#8217;obtenir des visas pour votre famille.<\/p>\n<p>Vous devez avoir entre 18 et 25 ans pour postuler pour un WHP.<\/p>\n<p>Il est important de noter qu&#8217;il ne peut pas y avoir plus de 2 000 personnes avec un WHP en m\u00eame temps \u00e0 Singapour : si votre candidature est refus\u00e9e, n&#8217;h\u00e9sitez pas \u00e0 la renouvel\u00e9 car des visas WHP se lib\u00e8rent tous les jours et vous aurez peut-\u00eatre plus de chance !<\/p>\n<p>Notez aussi que le WHP n&#8217;est pas rattach\u00e9 \u00e0 une entreprise contrairement aux autres visas : cela signifie que vous pouvez changer d&#8217;entreprise \u00e0 tout moment au cours des 6 mois.<\/p>\n<h4><span style=\"text-decoration: underline;\"><strong>Personalised Employment Pass (PEP)<\/strong><\/span><\/h4>\n<p>Le PEP est un EP personnel : il n&#8217;est pas rattach\u00e9 \u00e0 une entreprise mais \u00e0 vous-m\u00eame, ce qui fait que vous pouvez changer d&#8217;entreprise \u00e0 tout moment.<\/p>\n<p>Pour avoir une chance de l&#8217;obtenir, les candidats doivent avoir un salaire :<\/p>\n<ul>\n<li>d&#8217;au moins 12 000 SGD par mois s&#8217;ils sont actuellement en possession d&#8217;un EP.<\/li>\n<li>d&#8217;au moins 18 000 SGD par mois s&#8217;ils travaillent actuellement \u00e0 l&#8217;\u00e9tranger<\/li>\n<\/ul>\n<p>Le PEP n&#8217;est pas renouvelable : il n&#8217;est valable que pendant 3 ans et vous n&#8217;avez pas le droit d&#8217;entreprendre avec ce visa.<\/p>\n<p>Il y a certaines conditions \u00e0 respecter pour conserver votre PEP :<\/p>\n<ul>\n<li>Ne pas \u00eatre sans emploi pendant plus de 6 mois.<\/li>\n<li>Avoir un salaire d&#8217;au moins 144 000 SGD par an, quel que soit le nombre de mois travailler.<\/li>\n<li>Informer le Ministry of Manpower de tout changement d&#8217;employeur.<\/li>\n<\/ul>\n<p>Avec un PEP, vous pouvez obtenir des visas pour votre famille.<\/p>\n<h4><span style=\"text-decoration: underline;\"><strong>Working Permit (WP)<\/strong><\/span><\/h4>\n<p>Les Working Permit sont des visas de travail s&#8217;adressent \u00e0 des nationalit\u00e9s et \u00e0 des industries tr\u00e8s pr\u00e9cises (Aides domestique, Secteur de la construction, de la fabrication, chantiers navals&#8230;)<\/p>\n<p>Je ne vais pas trop rentrer dans les d\u00e9tails car si vous \u00eates Fran\u00e7ais, il n&#8217;y a aucune chance pour vous d&#8217;obtenir ce visa.<\/p>\n<h4><span style=\"text-decoration: underline;\"><strong>EntrePass<\/strong><\/span><\/h4>\n<p>L&#8217;EntrePass est un visa destin\u00e9 aux entrepreneurs qui souhaitent ouvrir une entreprise \u00e0 Singapour.<\/p>\n<p>La dur\u00e9e de validit\u00e9 d&#8217;un EntrePass est d&#8217;un an puis de 2 ans au second renouvellement.<\/p>\n<p>Ce visa vous permet aussi d&#8217;obtenir des visas pour votre famille sous certaines conditions :<\/p>\n<ul>\n<li>Obtenir un visa pour votre femme et vos enfants : votre entreprise doit d\u00e9penser 100 000 SGD par an et employer au moins 3 Singapouriens peu ou moyenne qualifi\u00e9e ou 1 Singapourien qualifi\u00e9.<\/li>\n<li>Obtenir un visa pour vos parents : votre entreprise doit d\u00e9penser 200 000 SGD par an et employer au moins 6 Singapouriens peu ou moyenne qualifi\u00e9e ou 2 Singapouriens qualifi\u00e9s.<\/li>\n<\/ul>\n<h4><span style=\"text-decoration: underline;\">Training Employment Pass<\/span><\/h4>\n<p>Il s&#8217;agit d&#8217;un visa de stage : contrairement au WHP, ce visa doit \u00eatre sponsoris\u00e9 par une entreprise.<\/p>\n<p>Pour pouvoir y pr\u00e9tendre, vous devez avoir un salaire d&#8217;au moins 3 000 SGD par mois.<\/p>\n<p>Le Training Employment Pass est valable jusqu&#8217;\u00e0 3 mois et il n&#8217;est pas renouvelable. Il ne vous permet pas non plus d&#8217;obtenir de visa pour votre famille.<\/p>\n<h4><span style=\"text-decoration: underline;\">Training Work Permit<\/span><\/h4>\n<p>Il s&#8217;agit d&#8217;un visa de stage : contrairement au WHP, ce visa doit \u00eatre sponsoris\u00e9 par une entreprise.<\/p>\n<p>Il n&#8217;y a pas de salaire minimum pour ce visa en revanche, c&#8217;est un visa qui s&#8217;adresse uniquement \u00e0 certaines nationalit\u00e9s et en \u00e9tant Fran\u00e7ais vous n&#8217;y aurez pas acc\u00e8s.<\/p>\n<p>Le Training Work Permit est valable jusqu&#8217;\u00e0 6 mois et il n&#8217;est pas renouvelable. Il ne vous permet pas non plus d&#8217;obtenir de visa pour votre famille.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>XI &#8211; La s\u00e9curit\u00e9<\/h2>\n<p>La s\u00e9curit\u00e9 \u00e0 Singapour n&#8217;est pas un probl\u00e8me, de jour comme de nuit.<\/p>\n<p>La Cit\u00e9-\u00c9tat poss\u00e8de des lois qui sont strictes et qu&#8217;elle applique avec fermet\u00e9. Contrairement \u00e0 d&#8217;autres pays qui peuvent se montrer moins regardant si vous \u00eates \u00e9tranger, Singapour ne plaisante pas avec la Loi : toute infraction est passible a minima d&#8217;une amende.<\/p>\n<p>Quelques lois auxquelles vous devez faire attention :<\/p>\n<ul>\n<li>Il est interdit de fumer dans les lieux publics : fumer dans la rue est autoriser \u00e0 condition de ne pas \u00eatre \u00e0 proximit\u00e9 de l&#8217;entr\u00e9e d&#8217;un b\u00e2timent et de ne pas jeter son m\u00e9got par terre&#8230; sinon c&#8217;est 500 SGD.<\/li>\n<li>La cigarette \u00e9lectronique est strictement interdite : m\u00eame en transit \u00e0 l&#8217;a\u00e9roport !<\/li>\n<li>Traverser en dehors du passage pi\u00e9ton si vous \u00eates \u00e0 moins de 50 m\u00e8tres de ceux-ci : 100 SGD.<\/li>\n<li>Manger et boire dans le m\u00e9tro : 500 SGD<\/li>\n<li>Cracher par terre : 1 000 SGD<\/li>\n<li>Jeter des d\u00e9tritus : 500 SGD<\/li>\n<li>Uriner dans la rue ou oublier de tirer la chasse dans des toilettes publiques : 1 000 SGD<\/li>\n<li>M\u00e2cher du chewing-gum : 1 000 SGD (ils sont d&#8217;ailleurs interdits \u00e0 la vente et \u00e0 l&#8217;importation).<\/li>\n<li>Les graffitis sont consid\u00e9r\u00e9s comme du vandalisme et punis de coups de b\u00e2tons.<\/li>\n<li>Possession de drogue : 20 000 SGD et\/ou 10 ans de prison. (Pour les trafiquants, c&#8217;est la peine de mort)<\/li>\n<\/ul>\n<p>La police est souvent en civil et n&#8217;est pas corrompue.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>XII &#8211; Informations Pratiques<\/h2>\n<p><em><strong>Dur\u00e9e de vol direct depuis Paris :<br \/>\n<\/strong><\/em>13 heures<\/p>\n<p><em><strong>D\u00e9calage horaire :<\/strong><\/em><br \/>\n+ 6h en \u00e9t\u00e9, + 7h en hiver.<\/p>\n<p><em><strong>H\u00e9bergement touristique :<\/strong><\/em><\/p>\n<p>Prix moyen d\u2019un h\u00f4tel 1 * \u00e0 Singapour :<strong> 27 SGD \/ nuit<\/strong> soit environ 17 euros<br \/>\nPrix moyen d\u2019un h\u00f4tel 5* \u00e0 Singapour :<strong> 290 SGD<\/strong>\u00a0<strong>\/ nuit\u00a0<\/strong>soit environ 184 euros<\/p>\n<p><em><strong>Devise :<\/strong><\/em><\/p>\n<p>\u00c0 Singapour, la monnaie est le SINGAPORE DOLLARS (SGD ou S$).<\/p>\n<p>La plupart des achats peuvent s\u2019effectuent en Cash ou par carte bancaire. Aucun probl\u00e8me pour trouver des distributeurs de billets Visa ou Mastercard.<\/p>\n<h4><em><strong>Sant\u00e9 :<\/strong><\/em><\/h4>\n<p>Aucun probl\u00e8me de ce c\u00f4t\u00e9-l\u00e0 : le syst\u00e8me de sant\u00e9 de Singapour est l\u2019un des meilleurs au monde, mais c\u2019est aussi l\u2019un des plus chers !<\/p>\n<p><em><strong>Vaccins recommand\u00e9s :\u00a0<\/strong><\/em><a href=\"https:\/\/www.pasteur.fr\/fr\/centre-medical\/preparer-son-voyage\/singapour\">Consulter le site de l\u2019Institut Pasteur<\/a><\/p>\n<h4><em><strong>Internet :<\/strong><\/em><\/h4>\n<p>Singapour est tr\u00e8s connect\u00e9e et le r\u00e9seau internet y est de bonne qualit\u00e9. Certains sites sont censur\u00e9s par le gouvernement : je vous recommande tout de m\u00eame d\u2019installer un VPN sur votre ordinateur et sur votre t\u00e9l\u00e9phone.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>XIII &#8211; Foire aux questions<\/h2>\n<p>Choisissez une cat\u00e9gorie ci-dessous pour faire appara\u00eetre les questions \/ r\u00e9ponses<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_content_element\" data-interval=\"0\">\n\t\t<div class=\"wpb_wrapper tabbed clearfix\" data-style=\"default\" data-spacing=\"default\" data-icon-size=\"\" data-full-width-line=\"\" data-color-scheme=\"accent-color\" data-alignment=\"left\">\n\t\t\t<ul class=\"wpb_tabs_nav ui-tabs-nav clearfix\"><li><a href=\"#tab-1594208071961-9\"><span>CAT\u00c9GORIES &gt;<\/span><\/a><\/li><li><a href=\"#tab-1594208072109-10\"><span>LOGEMENTS<\/span><\/a><\/li><\/ul>\n\n\t\t\t\n\t\t\t<div id=\"tab-categories\" data-tab-icon=\"\" class=\"wpb_tab ui-tabs-panel wpb_ui-tabs-hide clearfix\">\n\t\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t\t<\/div> \n\t\t\t<div id=\"tab-logements\" data-tab-icon=\"\" class=\"wpb_tab ui-tabs-panel wpb_ui-tabs-hide clearfix\">\n\t\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>Vous avez des questions concernant les logements \u00e0 Singapour ? N&#8217;h\u00e9sitez pas \u00e0 laisser un commentaire et j&#8217;essayerai de vous r\u00e9pondre !<\/p>\n<p><strong>Q : EST-IL FACILE DE TROUVER UN LOGEMENT ?<br \/>\n<\/strong>R : Oui ! Comme je le disais en introduction, j&#8217;ai personnellement trouv\u00e9 mon premier appartement en une seule journ\u00e9e !<\/p>\n<p>\u00c0 Singapour, il y a plus d&#8217;offres que de demande, ce qui permet de trouver rapidement un logement et de n\u00e9gocier les prix \u00e0 la baisse.<\/p>\n<p>Pour trouver un logement, vous pouvez utiliser <a href=\"https:\/\/www.propertyguru.com.sg\/\">PropertyGuru<\/a>, <a href=\"https:\/\/www.iproperty.com.sg\/\">iProperty<\/a>, <a href=\"https:\/\/www.stproperty.sg\/\">STProperty<\/a>, <a href=\"https:\/\/www.99.co\/\">99.co<\/a>. Si vous cherchez une colocation d\u00e9j\u00e0 existante, vous pouvez rejoindre le groupe Facebook <a href=\"https:\/\/www.facebook.com\/groups\/7813395019\/\">SingaFrog<\/a>.<\/p>\n<p>Ne payez jamais avant d&#8217;avoir vu l&#8217;appartement : regarder les annonces avant de venir \u00e0 Singapour et prenez rendez-vous pour le jour de votre arriv\u00e9e.<\/p>\n<p><strong>Q : DANS QUEL QUARTIER VIVRE \u00c0 SINGAPOUR ?<\/strong><br \/>\nR : Singapour est une \u00eele relativement petite : il est possible de la traverser du nord au sud et d&#8217;ouest en est en moins d&#8217;une heure (en voiture comme en m\u00e9tro). D\u00e8s lors, le choix du quartier d\u00e9pendra principalement de votre bureau, de l&#8217;\u00e9cole de vos enfants et du loyer que vous \u00eates pr\u00eat \u00e0 payer.<\/p>\n<p>Certains quartiers sont plus populaires que d&#8217;autres aupr\u00e8s des familles fran\u00e7aises :<\/p>\n<ul>\n<li><strong>Serangoon Gardens :<\/strong> Notamment gr\u00e2ce \u00e0 l&#8217;IFS (International French School, ex Lyc\u00e9e Fran\u00e7ais) et aux nombreux services et commerces qui visent la communaut\u00e9 fran\u00e7aise. C&#8217;est un quartier plut\u00f4t cher et si vous n&#8217;avez pas d&#8217;enfants, je ne vous le recommande pas sp\u00e9cialement.<\/li>\n<li><strong>Bishan \/ Ang Mo Kio \/ Kovan :<\/strong> Trois quartiers assez proches de Serangoon Gardens qui peuvent donc \u00e9galement vous int\u00e9resser si vos enfants vont \u00e0 l&#8217;IFS. Beaucoup plus de choix parmi les condos et les loyers sont moins chers.<\/li>\n<li><strong>East Coast : <\/strong>Si vous aimez la plage, East Coast est le quartier qu&#8217;il vous faut ! En revanche, le quartier est uniquement desservi par bus, pas encore de m\u00e9tro !<\/li>\n<li><strong>Bukit Timah <\/strong><strong>: <\/strong>Le quartier des millionnaires avec de tr\u00e8s bons restaurants. Principalement compos\u00e9 de villas et de quelques condos !<\/li>\n<li><strong>Orchard \/ River Valley<\/strong> : Deux quartiers internationaux du centre-ville. Relativement cher mais vous \u00eates dans le centre de Singapour.<\/li>\n<li><strong>Geylang : <\/strong>Un quartier tr\u00e8s anim\u00e9 qui attire beaucoup de jeunes car il y a beaucoup de choix de colocations et qu&#8217;il est assez pr\u00e8s du centre de Singapour.<\/li>\n<li><strong>Holland Village : <\/strong>Un quartier sympa, proche du jardin botanique et \u00e0 quelques minutes de voiture d&#8217;Orchard.<\/li>\n<li><strong>Tiong Bahru \/ Everton Park : <\/strong>Deux quartiers assez chers car \u00e0 la mode : plein de petites boutiques et restaurants cool, proche du centre-ville.<\/li>\n<li><strong>Tanjong Pagar :<\/strong> Le quartier le plus proche du centre de Singapour. Id\u00e9al pour les c\u00e9libataires ou les couples, mais pas vraiment pour les familles. Les appartements y sont chers et petits.<\/li>\n<li><strong>Sentosa Cove<\/strong> <strong>:<\/strong> Le quartier des ultras-riches. Un grand nombre de maisons en bord de mer, mais vous \u00eates loin de tout, m\u00eame en voiture.<\/li>\n<\/ul>\n<p>Certains quartiers sont plus &#8220;locaux&#8221; :<\/p>\n<ul>\n<li><strong>Jurong :<\/strong> situ\u00e9 dans le sud de Singapour, Jurong est un quartier plut\u00f4t industriel. Il doit bien y avoir quelques logements mais ce n&#8217;est vraiment pas un quartier attirant.<\/li>\n<li><strong>Punggol :<\/strong> Situ\u00e9 dans le nord de Singapour, c&#8217;est un quartier plut\u00f4t calme. Toutefois, il n&#8217;est pas rare que des avions de chasse viennent troubler le calme (la base a\u00e9rienne est \u00e0 proximit\u00e9). Pour y avoir habit\u00e9 pendant de nombreuses ann\u00e9es, c&#8217;est un quartier que je recommande, m\u00eame s&#8217;il est un peu excentr\u00e9.<\/li>\n<li><strong>Woodlands :<\/strong> \u00c0 l&#8217;ouest de Singapour, c&#8217;est le quartier le plus proche de la Malaisie. Un des quartiers les plus &#8220;locaux&#8221; de Singapour. Des loyers tr\u00e8s abordables.<\/li>\n<li><strong>Tampines :<\/strong> Un autre quartier tr\u00e8s &#8220;local&#8221;. Les loyers sont \u00e9galement tr\u00e8s abordables. Vous \u00eates \u00e0 proximit\u00e9 imm\u00e9diate de l&#8217;a\u00e9roport de Changi, id\u00e9al si vous voyagez beaucoup !<\/li>\n<\/ul>\n<p><strong>Q : EST-IL FACILE DE TROUVER UNE COLOCATION ?<\/strong><br \/>\nR : Oui : les loyers \u00e0 Singapour sont tr\u00e8s \u00e9lev\u00e9s. Par cons\u00e9quent, de nombreux jeunes actifs ou c\u00e9libataires se tournent vers la colocation.<\/p>\n<p>Si vous cherchez une colocation d\u00e9j\u00e0 existante, vous pouvez rejoindre le groupe Facebook <a href=\"https:\/\/www.facebook.com\/groups\/7813395019\/\">SingaFrog<\/a>.<\/p>\n<p>Voici quelques d\u00e9finitions pour vous aider \u00e0 lire les annonces de colocation :<\/p>\n<ul>\n<li>Utilities : il s&#8217;agit des charges. Renseignez-vous pour savoir si elles sont comprises ou non.<\/li>\n<li>No [Chinese \/ Indian \/ French \/ \u2026 ] : Certains propri\u00e9taires ne souhaitent pas louer \u00e0 certaines personnes sur la base de crit\u00e8res raciaux ou de nationalit\u00e9s&#8230;<\/li>\n<li>No couple : les couples ne sont pas les bienvenues dans toutes les colocations. Pr\u00e9cisez bien votre situation pour \u00e9viter les mauvaises surprises!<\/li>\n<li>No cooking : Non, ce n&#8217;est pas une blague. Dans certains logements, il est interdit de cuisiner ! Vous avez le droit de manger, mais vous devez acheter votre repas \u00e0 l&#8217;ext\u00e9rieur.<\/li>\n<li>No visits \/ No staying : On vous interdit de ramener quelqu&#8217;un dans le logement.<\/li>\n<li>No owner \/ No owner staying : cela signifie que le propri\u00e9taire n&#8217;habitera pas avec vous. C&#8217;est en effet une pratique \u00e0 Singapour : les propri\u00e9taires font de la colocation pour amortir le prix de leur logement.<\/li>\n<li>Common Room : chambre individuelle avec salle de bain partag\u00e9e (vous \u00eates seul dans une common room mais vous partagez la salle de bain avec les autres colocataires).<\/li>\n<li>Master Bedroom : grande chambre avec salle de bain privative.<\/li>\n<\/ul>\n<p><strong>Q : L&#8217;AGENT IMMOBILIER EST-IL OBLIGATOIRE ?<\/strong><br \/>\nR : Non, non et encore non ! Avoir un agent immobilier \u00e0 Singapour n&#8217;est pas obligatoire pour trouver un logement.<\/p>\n<p>Lorsque vous r\u00e9pondez \u00e0 une annonce sur un site immobilier, vous r\u00e9pondez soit \u00e0 un propri\u00e9taire, soit \u00e0 l&#8217;agent immobilier du propri\u00e9taire (c&#8217;est-\u00e0-dire qu&#8217;il est pay\u00e9 par le propri\u00e9taire et non par vous).<\/p>\n<p>Le seul int\u00e9r\u00eat selon moi d&#8217;avoir un agent immobilier c&#8217;est si vous n&#8217;avez pas le temps de faire les recherches vous-m\u00eames sur <a href=\"https:\/\/www.propertyguru.com.sg\/\">PropertyGuru<\/a>, <a href=\"https:\/\/www.iproperty.com.sg\/\">iProperty<\/a>, <a href=\"https:\/\/www.stproperty.sg\/\">STProperty<\/a>, <a href=\"https:\/\/www.99.co\/\">99.co<\/a>. Si vous faites les recherches par vous-m\u00eames, ne prenez pas d&#8217;agent !<\/p>\n<p>Attention : Un agent ne peut pas collecter des frais aupr\u00e8s du propri\u00e9taire et du locataire, c&#8217;est ill\u00e9gal !<\/p>\n<p>Attention aussi \u00e0 une arnaque fr\u00e9quente : Vous r\u00e9pondez \u00e0 une annonce sur l&#8217;un de ces sites et l&#8217;agent immobilier vous r\u00e9pond que ce bien n&#8217;est plus disponible mais qu&#8217;il peut vous en pr\u00e9senter d&#8217;autres : si vous acceptez, il devient votre agent !<\/p>\n<p><strong>Q : AS-TU DES CONSEILS POUR CHOISIR UN LOGEMENT ?<\/strong><br \/>\nR : Oui, j&#8217;ai quelques conseils :<\/p>\n<ul>\n<li>Lisez votre contrat avant de le signer ! Tout est \u00e9crit dedans : si une clause ne vous convient pas, alors n\u00e9gociez l\u00e0 !<\/li>\n<li>N\u00e9gociez votre loyer : \u00e0 Singapour, les loyers de tous les appartements sont publics : <a href=\"https:\/\/www.ura.gov.sg\/realEstateIIWeb\/resiRental\/search.action\">ils sont publi\u00e9s chaque mois sur un site gouvernemental<\/a>. Regardez combien payent vos voisins et n\u00e9gociez les prix !<\/li>\n<li>Ne versez pas d&#8217;argent tant que vous n&#8217;avez pas vu l&#8217;appartement !<\/li>\n<li>R\u00e9fl\u00e9chissez \u00e0 votre lifestyle : \u00eates-vous plut\u00f4t du genre \u00e0 voyager tous les week-ends ou \u00e0 rester chez vous ? Si vous voyagez, peut-\u00eatre qu&#8217;il n&#8217;est pas n\u00e9cessaire de payer 25% plus cher pour un condo bien \u00e9quip\u00e9 si vous ne l&#8217;utilisez pas.<\/li>\n<li>Ne signez pas de Letter of Intent (LOI) si vous n&#8217;\u00eates pas s\u00fbr \u00e0 100% de prendre l&#8217;appartement. Une LOI est un contrat : si vous changez d&#8217;avis et que vous ne prenez pas l&#8217;appartement, vous devrez g\u00e9n\u00e9ralement payer un mois de loyer au propri\u00e9taire.<\/li>\n<li>Si vous \u00eates \u00e0 Singapour que pour quelques mois \/ ann\u00e9es (ce qui est le plus souvent le cas) alors orientez-vous uniquement vers les appartements meubl\u00e9s (fully-furnished).<\/li>\n<li>Visitez le quartier et v\u00e9rifiez les distances annonc\u00e9es (5 minutes du m\u00e9tro peuvent vite se transformer en 15 minutes).<\/li>\n<li>Lors de l&#8217;\u00e9tat des lieux, v\u00e9rifier tout en d\u00e9tail et au moindre probl\u00e8me contacter le propri\u00e9taire ou son agent.<\/li>\n<\/ul>\n<p><strong>Q : DE QUELS DOCUMENTS AI-JE BESOIN POUR LOUER UN LOGEMENT ?<\/strong><br \/>\nR : Contrairement \u00e0 la France, les propri\u00e9taires singapouriens ne vous demanderont pas vos fiches de paies ou de garants : ils n&#8217;en ont pas besoin car si vous ne payez pas votre loyer, vous serez expuls\u00e9 dans la journ\u00e9e.<\/p>\n<p>Vous aurez juste besoin de fournir une copie de votre passeport et de votre visa singapourien (EP \/ S Pass &#8230;)<\/p>\n<p><strong>Q : \u00c0 COMBIEN DE MOIS DE LOYER S&#8217;\u00c9L\u00c8VE LA CAUTION ?<\/strong><br \/>\nR : La caution est de 1 mois pour un contrat d&#8217;un an. De 2 mois si c&#8217;est un contrat de 2 ans mais c&#8217;est un point facilement n\u00e9gociable. Le loyer doit \u00eatre pay\u00e9 avec un mois d\u2019avance et vous serez expuls\u00e9 sur-le-champ si vous ne le payez pas.<\/p>\n<p><strong>Q : QUI PAYE LES FRAIS D&#8217;AGENTS DANS LE CADRE D&#8217;UNE LOCATION ?<\/strong><br \/>\nR : Si vous n&#8217;avez pas engag\u00e9 d&#8217;agent pour faire vos recherches, alors vous n&#8217;avez pas \u00e0 payer de frais d&#8217;agent (c&#8217;est le propri\u00e9taire qui les paiera).<\/p>\n<p>Lorsque vous r\u00e9pondrez \u00e0 des annonces, n&#8217;h\u00e9sitez pas \u00e0 demander \u00e0 votre interlocuteur s&#8217;il est bien l&#8217;agent du propri\u00e9taire. Si ce n&#8217;est pas le cas, cela signifie que si vous passez par lui, vous devrez payer des frais d&#8217;agents.<\/p>\n<p><strong>Q : QU&#8217;EST-CE QUE LE STAMP DUTY ? QUI LE PAYE ?<\/strong><br \/>\nR : Le Stamp Duty c&#8217;est l\u2019enregistrement du contrat aupr\u00e8s des autorit\u00e9s \u00e0 Singapour. Sans le Stamp Duty, votre contrat ne sera pas reconnu par la justice et vous serez h\u00e9berg\u00e9 ill\u00e9galement.<\/p>\n<p>Le Stamp Duty est pay\u00e9 soit par le propri\u00e9taire, soit par le locataire, soit par les deux. Votre contrat doit pr\u00e9ciser qui devra le payer et surtout une copie du Stamp Duty doit vous \u00eatre remise.<\/p>\n<p>Attention : le stamp duty, ce n&#8217;est que pour les appartements, pas pour la location d&#8217;une chambre dans une colocation ! Faire payer un stamp duty dans une colocation est ill\u00e9gal.<\/p>\n<p><strong>Q : QU&#8217;EST-CE QUE JE DOIS V\u00c9RIFIER DANS LE CONTRAT DE LOCATION ?<\/strong><br \/>\nR : Vous devez absolument lire votre contrat en d\u00e9tail. Vous devez v\u00e9rifier :<\/p>\n<ul>\n<li>Que les frais d&#8217;agents seront pay\u00e9s par le propri\u00e9taire. (dans le cas o\u00f9 vous n&#8217;avez pas engag\u00e9 votre propre agent).<\/li>\n<li>Que vous allez payer un mois apr\u00e8s l&#8217;autre.<\/li>\n<li>Qu&#8217;il y a bien une clause diplomatique : c&#8217;est-\u00e0-dire que si vous perdez votre visa et donc votre droit de rester \u00e0 Singapour, le contrat s&#8217;arr\u00eate.<\/li>\n<li>Qu&#8217;il n&#8217;y a pas de frais d&#8217;agent en cas de renouvellement du bail.<\/li>\n<li>Que la franchise en cas de travaux \/ pannes ne d\u00e9passe pas les 150 SGD.<\/li>\n<li>Si les clims de votre appartement sont vieilles, vous devez imp\u00e9rativement faire note au contrat que les frais de maintenance \/ de r\u00e9parations seront a la charge du propri\u00e9taire.<\/li>\n<li>Que l&#8217;appartement n&#8217;est pas en vente. Sinon vous allez subir des visites d&#8217;acheteur et surtout, le nouveau propri\u00e9taire pourra vous mettre \u00e0 la porte !<\/li>\n<\/ul>\n<p>Gardez \u00e0 l&#8217;esprit que tout est n\u00e9gociable \u00e0 Singapour, donc n&#8217;h\u00e9sitez pas \u00e0 faire supprimer des clauses que vous trouvez aberrantes.<\/p>\n<p><strong>Q : L&#8217;AGENT ME DEMANDE DE VERSER UN ACOMPTE \/ ME R\u00c9CLAME PLUSIEURS MOIS D&#8217;AVANCE. DOIS-JE PAYER ?<\/strong><br \/>\nR : NON ! Premi\u00e8rement, un agent n&#8217;a pas le droit d&#8217;encaisser de l&#8217;argent de la part d&#8217;un locataire et deuxi\u00e8mement, votre signature suffit \u00e0 s\u00e9curiser la transaction.<\/p>\n<p>Il n&#8217;est pas d&#8217;usage \u00e0 Singapour de payer plusieurs mois d&#8217;avance, ce n&#8217;est pas interdit, mais ce n&#8217;est pas l&#8217;usage ! Ne le faites pas : si jamais votre propri\u00e9taire d\u00e9cide de vendre et de dispara\u00eetre, vous ne reverrez jamais votre argent et vous serez mis dehors par le nouveau propri\u00e9taire.<\/p>\n<p><strong>Q : DOIS-JE VERSER LA CAUTION \u00c0 L&#8217;AGENT ?<\/strong><br \/>\nR : NON ! Les agents ne sont pas autoris\u00e9s \u00e0 encaisser les cautions ou les loyers des locataires. Ils ne peuvent recevoir que les frais d&#8217;agents, si vous avez engag\u00e9 votre propre agent.<\/p>\n<p><strong>Q :\u00a0 L&#8217;INVENTAIRE ET L&#8217;\u00c9TAT DES LIEUX EST-IL OBLIGATOIRE ?<\/strong><br \/>\nR : Cela d\u00e9pend : souhaitez-vous revoir votre caution ? Si oui, alors l&#8217;inventaire et l&#8217;\u00e9tat des lieux est indispensable !<\/p>\n<p><strong>Q : L&#8217;AGENT \/ LE PROPRI\u00c9TAIRE A-T-IL LE DROIT D&#8217;ORGANISER DES VISITES CHEZ MOI POUR VENDRE SON APPARTEMENT ?<\/strong><br \/>\nR : Si c&#8217;est inscrit dans votre contrat (et le plus souvent, \u00e7a l&#8217;est) alors oui, il a le droit d&#8217;organiser des visites pour vendre son appartement.<\/p>\n<p>C&#8217;est pour cela que je vous conseille de v\u00e9rifier si l&#8217;appartement est en vente ou non. S&#8217;il est en vente, alors il vaut mieux en chercher un autre !<\/p>\n<p><strong>Q : L&#8217;AGENT \/ LE PROPRI\u00c9TAIRE ME DEMANDE DE PAYER UNE SOCI\u00c9T\u00c9 DE NETTOYAGE AVANT MON D\u00c9PART. EST-CE L\u00c9GAL ?<\/strong><br \/>\nR : C&#8217;est l\u00e9gal oui : si c&#8217;est dans votre contrat et que vous l&#8217;avez sign\u00e9, alors c&#8217;est trop tard ! Pour \u00e9viter tout probl\u00e8me sur la qualit\u00e9 du nettoyage, je vous recommande m\u00eame de demander au propri\u00e9taire s&#8217;il a une entreprise pr\u00e9f\u00e9r\u00e9e.<\/p>\n<p>Si vous \u00eates sur le point de signer votre bail et que cette clause est pr\u00e9sente, je vous recommande de n\u00e9gocier avec le propri\u00e9taire ou son agent pour la faire retirer.<\/p>\n<p><strong>Q : L&#8217;ADRESSE DU PROPRI\u00c9TAIRE DOIT-ELLE FIGURER SUR LE CONTRAT ?<\/strong><br \/>\nR : Oui, c&#8217;est obligatoire. En cas de probl\u00e8me, si vous devez aller au tribunal, ils auront besoin de l&#8217;adresse du propri\u00e9taire pour les mises en demeure. Concernant son num\u00e9ro de t\u00e9l\u00e9phone, ce n&#8217;est pas obligatoire.<\/p>\n<p>Attention : Si le propri\u00e9taire vit \u00e0 l&#8217;\u00e9tranger, le tribunal des affaires courantes (Small Claim Tribunal) ne sera pas comp\u00e9tent et vous serez oblig\u00e9 d&#8217;engager un avocat pour aller en justice.<\/p>\n<p><strong>Q : QUEL RECOURS EN CAS DE LITIGES ?<\/strong><br \/>\nR : En cas de litige avec votre propri\u00e9taire, vous devez aller au tribunal des affaires courantes (Small Claim Tribunal). Il n&#8217;est comp\u00e9tent que pour les affaires jusqu&#8217;\u00e0 10 000 SGD.<\/p>\n<p>La plupart du temps, la simple convocation du Small Claim Tribunal suffira \u00e0 r\u00e9gler le diff\u00e9rend.<\/p>\n<p>Si vous \u00eates s\u00fbr d&#8217;\u00eatre dans votre droit, alors n&#8217;h\u00e9sitez pas \u00e0 aller jusqu&#8217;au bout de la proc\u00e9dure, mais attention : \u00e0 Singapour, la loi est plus favorable aux propri\u00e9taires.<\/p>\n<p><strong>Q : EST-CE QUE JE PEUX LOUER UN LOGEMENT POUR SEULEMENT 3 MOIS ?<\/strong><br \/>\nR : Depuis juillet 2017, c&#8217;est possible. Certains agents immobiliers \/ propri\u00e9taires ne sont pas encore au courant, alors n&#8217;h\u00e9sitez pas \u00e0 insister un peu.<\/p>\n<p>\u00c0 Singapour, ce n&#8217;est pas comme en France : quand vous signez un contrat pour 2 ans, vous ne pouvez pas donner un pr\u00e9avis d&#8217;un mois au bout de 6 mois pour quitter l&#8217;appartement. Vous devrez soit trouver un arrangement avec le propri\u00e9taire ou payer les mois restants.<\/p>\n<p><strong>Q : EST-CE QUE JE PEUX METTRE MON LOGEMENT SUR AIRBNB ?<\/strong><br \/>\nR : NON : Airbnb est ill\u00e9gale \u00e0 Singapour ! En mettant votre logement sur Airbnb, vous devrez payer des amendes \u00e0 l&#8217;\u00c9tat, au propri\u00e9taire, et m\u00eame au management du condo !<\/p>\n<p><strong>Q : \u00c0 COMBIEN S&#8217;\u00c9L\u00c8VE LA TAXE D&#8217;HABITATION \u00c0 SINGAPOUR ?<\/strong><br \/>\nR : Il n&#8217;y a pas de taxe d&#8217;habitation \u00e0 Singapour.<\/p>\n<p><strong>Q : SI JE RENOUVELLE MON CONTRAT, DOIS-JE PAYER DES FRAIS D&#8217;AGENTS ?<\/strong><br \/>\nR : Encore une fois, cela d\u00e9pend de votre contrat ! Si c&#8217;est dans votre contrat et que vous l&#8217;avez sign\u00e9 alors oui !<\/p>\n<p>Si vous n&#8217;avez pas encore sign\u00e9 votre contrat, alors faites retirer cette clause du contrat ! \u00c0 moins que vous souhaiter donnez une commission qui \u00e9quivaut \u00e0 1 mois de loyer \u00e0 l&#8217;agent pour qu&#8217;il change la date sur le contrat&#8230;<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t\t<\/div> \n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>XIV &#8211; La carte<\/h2>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div id=\"map_6a04774ce2fec\" style=\"height: 400px;\" class=\"nectar-leaflet-map\" data-infowindow-start-open=\"\" data-dark-color-scheme=\"\" data-marker-style=\"default\" data-nectar-marker-color=\"extra-color-1\" data-ultra-flat=\"\" data-greyscale=\"\" data-extra-color=\"\" data-enable-animation=\"false\" data-enable-zoom=\"\" data-zoom-level=\"11\" data-center-lat=\"1.356832\" data-center-lng=\"103.826455\" data-marker-img=\"\"><\/div><div class=\"map_6a04774ce2fec map-marker-list\"><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"1.4063175307996594\" data-lng=\"103.90195318571753\" data-mapinfo=\"Condo Watertown<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"1.4053588997916466\" data-lng=\"103.89970914992787\" data-mapinfo=\"Condo A Treasure Trove<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"1.3148131830069338\" data-lng=\"103.88847829017324\" data-mapinfo=\"Condo Centra Loft<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"1.2817855017419346\" data-lng=\"103.86397113869504\" data-mapinfo=\"Garden by the bay<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"1.2837717219484426\" data-lng=\"103.86084641494026\" data-mapinfo=\"Bar CE LA VI<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"1.2867497976766678\" data-lng=\"103.85445556533841\" data-mapinfo=\"Merlion Park<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"1.2817919254302979\" data-lng=\"103.843994140625\" data-mapinfo=\"Chinatown<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"1.3066476\" data-lng=\"103.8492691\" data-mapinfo=\"Little India<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"1.2538942170924763\" data-lng=\"103.81399867936705\" data-mapinfo=\"Sentosa<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"1.2710747718811035\" data-lng=\"103.81935119628906\" data-mapinfo=\"Singapore Cable Car<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"1.2540444135665894\" data-lng=\"103.8228759765625\" data-mapinfo=\"Universal Studio<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"1.3575573\" data-lng=\"103.9884703\" data-mapinfo=\"A\u00e9roport de Changi\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"\u00c0 l'origine je devais y rester 6 mois : j'y ai v\u00e9cu pendant quasiment 4 ans. Dans cet article, je vous parle de ma vie \u00e0 Singapour, cette cit\u00e9-\u00c9tat au...","protected":false},"author":1,"featured_media":6030,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-222","post","type-post","status-publish","format-standard","has-post-thumbnail","category-voyages"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\ud83c\uddf8\ud83c\uddecMa vie \u00e0 Singapour - Guillaume TEILLET<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guillaumeteillet.com\/en\/ma-vie-a-singapour\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\uddf8\ud83c\uddecMa vie \u00e0 Singapour - Guillaume TEILLET\" \/>\n<meta property=\"og:description\" content=\"Nulla sed mi leo, sit amet molestie nulla. Phasellus lobortis blandit ipsum, at adipiscing eros porta quis. Phasellus in nisi ipsum, quis dapibus magna\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guillaumeteillet.com\/en\/ma-vie-a-singapour\/\" \/>\n<meta property=\"og:site_name\" content=\"Guillaume TEILLET\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-23T16:20:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-08T12:47:05+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/themenectar.com\/demo\/salient-blog\/wp-content\/uploads\/2013\/03\/tumblr_n6rzpcsMk41st5lhmo1_12802.jpg\" \/>\n<meta name=\"author\" content=\"Guillaume Teillet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guillaume Teillet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"50 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/\",\"url\":\"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/\",\"name\":\"\ud83c\uddf8\ud83c\uddecMa vie \u00e0 Singapour - Guillaume TEILLET\",\"isPartOf\":{\"@id\":\"https:\/\/guillaumeteillet.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_140624.jpg\",\"datePublished\":\"2017-03-23T16:20:09+00:00\",\"dateModified\":\"2020-07-08T12:47:05+00:00\",\"author\":{\"@id\":\"https:\/\/guillaumeteillet.com\/#\/schema\/person\/27fe48f08db74c8dee381b5f2277534f\"},\"breadcrumb\":{\"@id\":\"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/#primaryimage\",\"url\":\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_140624.jpg\",\"contentUrl\":\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_140624.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\/\/guillaumeteillet.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ud83c\uddf8\ud83c\uddecMa vie \u00e0 Singapour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/guillaumeteillet.com\/#website\",\"url\":\"https:\/\/guillaumeteillet.com\/\",\"name\":\"Guillaume TEILLET\",\"description\":\"Cr\u00e9er - Entreprendre - Investir - Partager\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/guillaumeteillet.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/guillaumeteillet.com\/#\/schema\/person\/27fe48f08db74c8dee381b5f2277534f\",\"name\":\"Guillaume Teillet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/guillaumeteillet.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9075bedaaadc1fe3829c3f7f40c99480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9075bedaaadc1fe3829c3f7f40c99480?s=96&d=mm&r=g\",\"caption\":\"Guillaume Teillet\"},\"sameAs\":[\"https:\/\/www.guillaumeteillet.com\"],\"url\":\"https:\/\/guillaumeteillet.com\/en\/author\/guillaume-teillet\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83c\uddf8\ud83c\uddecMa vie \u00e0 Singapour - Guillaume TEILLET","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guillaumeteillet.com\/en\/ma-vie-a-singapour\/","og_locale":"en_US","og_type":"article","og_title":"\ud83c\uddf8\ud83c\uddecMa vie \u00e0 Singapour - Guillaume TEILLET","og_description":"Nulla sed mi leo, sit amet molestie nulla. Phasellus lobortis blandit ipsum, at adipiscing eros porta quis. Phasellus in nisi ipsum, quis dapibus magna","og_url":"https:\/\/guillaumeteillet.com\/en\/ma-vie-a-singapour\/","og_site_name":"Guillaume TEILLET","article_published_time":"2017-03-23T16:20:09+00:00","article_modified_time":"2020-07-08T12:47:05+00:00","og_image":[{"url":"http:\/\/themenectar.com\/demo\/salient-blog\/wp-content\/uploads\/2013\/03\/tumblr_n6rzpcsMk41st5lhmo1_12802.jpg","type":"","width":"","height":""}],"author":"Guillaume Teillet","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Guillaume Teillet","Est. reading time":"50 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/","url":"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/","name":"\ud83c\uddf8\ud83c\uddecMa vie \u00e0 Singapour - Guillaume TEILLET","isPartOf":{"@id":"https:\/\/guillaumeteillet.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/#primaryimage"},"image":{"@id":"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/#primaryimage"},"thumbnailUrl":"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_140624.jpg","datePublished":"2017-03-23T16:20:09+00:00","dateModified":"2020-07-08T12:47:05+00:00","author":{"@id":"https:\/\/guillaumeteillet.com\/#\/schema\/person\/27fe48f08db74c8dee381b5f2277534f"},"breadcrumb":{"@id":"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/#primaryimage","url":"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_140624.jpg","contentUrl":"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2017\/03\/IMG_20160522_140624.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/guillaumeteillet.com\/ma-vie-a-singapour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/guillaumeteillet.com\/"},{"@type":"ListItem","position":2,"name":"\ud83c\uddf8\ud83c\uddecMa vie \u00e0 Singapour"}]},{"@type":"WebSite","@id":"https:\/\/guillaumeteillet.com\/#website","url":"https:\/\/guillaumeteillet.com\/","name":"Guillaume TEILLET","description":"Cr\u00e9er - Entreprendre - Investir - Partager","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guillaumeteillet.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/guillaumeteillet.com\/#\/schema\/person\/27fe48f08db74c8dee381b5f2277534f","name":"Guillaume Teillet","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/guillaumeteillet.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9075bedaaadc1fe3829c3f7f40c99480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9075bedaaadc1fe3829c3f7f40c99480?s=96&d=mm&r=g","caption":"Guillaume Teillet"},"sameAs":["https:\/\/www.guillaumeteillet.com"],"url":"https:\/\/guillaumeteillet.com\/en\/author\/guillaume-teillet\/"}]}},"_links":{"self":[{"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/posts\/222"}],"collection":[{"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/comments?post=222"}],"version-history":[{"count":166,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/posts\/222\/revisions"}],"predecessor-version":[{"id":6558,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/posts\/222\/revisions\/6558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/media\/6030"}],"wp:attachment":[{"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/media?parent=222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/categories?post=222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/tags?post=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}