{"id":7037,"date":"2020-09-28T10:30:01","date_gmt":"2020-09-28T08:30:01","guid":{"rendered":"https:\/\/www.guillaumeteillet.com\/?p=7037"},"modified":"2020-09-23T17:23:32","modified_gmt":"2020-09-23T15:23:32","slug":"roadtrip-en-france-neaux","status":"publish","type":"post","link":"https:\/\/guillaumeteillet.com\/en\/roadtrip-en-france-neaux\/","title":{"rendered":"\ud83d\ude97 Roadtrip en France #3 : Neaux"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">minutes<br \/><br \/><\/span><\/span>\n\t\t<div id=\"fws_6a0476a5d7ce4\"  data-column-margin=\"default\" data-midnight=\"dark\"  data-bg-mobile-hidden=\"\" class=\"wpb_row vc_row-fluid vc_row standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay\" ><\/div><\/div><div class=\"col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding\"  data-t-w-inherits=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-border-animation=\"\" data-border-animation-delay=\"\" data-border-width=\"none\" data-border-style=\"solid\" data-border-color=\"\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p><em>Cet article est le troisi\u00e8me d&#8217;une s\u00e9rie 6 articles qui retracent mon roadtrip en France (du 17 Juin au 4 Juillet 2020)<\/em>.<em> Vous pouvez : <a href=\"https:\/\/guillaumeteillet.com\/en\/roadtrip-en-france-avignon\/\">Lire l&#8217;\u00e9pisode 1<\/a>,\u00a0 <a href=\"https:\/\/guillaumeteillet.com\/en\/roadtrip-en-france-vienne\/\">Lire l&#8217;\u00e9pisode 2<\/a>.<\/em><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h3><strong>I &#8211; Direction Neaux !<\/strong><\/h3>\n<p><a href=\"https:\/\/guillaumeteillet.com\/en\/roadtrip-en-france-vienne\/\">Suite \u00e0 notre m\u00e9saventure \u00e0 Vienne<\/a>, nous avons trouv\u00e9 refuge dans un h\u00f4tel Ibis au nord de Vienne afin de pouvoir se reposer compl\u00e8tement avant de reprendre la route.<\/p>\n<p>Cette \u00e9tape Vienne &#8211; Neaux \u00e9tait l&#8217;une des plus courtes de notre roadtrip : Nous avons quitt\u00e9 l&#8217;h\u00f4tel apr\u00e8s le d\u00e9jeuner vers 14h et nous sommes arriv\u00e9 au g\u00eete vers 16h30.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7090\" src=\"https:\/\/www.guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/Screenshot-2020-09-03-at-15.08.05-1024x796.png\" alt=\"\" width=\"600\" height=\"466\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/Screenshot-2020-09-03-at-15.08.05-1024x796.png 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/Screenshot-2020-09-03-at-15.08.05-300x233.png 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/Screenshot-2020-09-03-at-15.08.05-768x597.png 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/Screenshot-2020-09-03-at-15.08.05.png 1506w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>La carte du trajet<\/em><\/p>\n<h3><strong>II &#8211; Notre logement \u00e0 Neaux<\/strong><\/h3>\n<p>Pour cette \u00e9tape dans la campagne Roannaise nous avions r\u00e9serv\u00e9 <a href=\"https:\/\/www.airbnb.fr\/associates\/92455?s=67&amp;c=.pi115.pk0_9&amp;a4ptk=16690_0_9_92455&amp;af=115\">un logement perch\u00e9 sur une colline<\/a> qui offre une vue imprenable sur un paysage vallonn\u00e9.<\/p>\n<p>La propri\u00e9taire, V\u00e9ronique, nous a accueillis et nous a pr\u00e9sent\u00e9 son logement et son fonctionnement : c&#8217;est sans doute l&#8217;un des meilleur airbnb dans lequel j&#8217;ai s\u00e9journ\u00e9 jusqu&#8217;\u00e0 pr\u00e9sent.<\/p>\n<p>Tout d&#8217;abord, parlons de la vue : elle est extraordinaire ! J&#8217;ai ador\u00e9 me mettre sur la terrasse pour travailler comme vous pouvez le voir :<\/p>\n<table style=\"width: 100%; border-collapse: collapse; border-color: #ffffff; background-color: #ffffff;\">\n<tbody style=\"border-color: #ffffff; background-color: #ffffff;\">\n<tr style=\"border-color: #ffffff; background-color: #ffffff;\">\n<td style=\"width: 50%; border-color: #ffffff; background-color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7080 alignright\" src=\"https:\/\/www.guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1892-589x1024.jpg\" alt=\"\" width=\"300\" height=\"522\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1892-589x1024.jpg 589w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1892-300x522.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1892-173x300.jpg 173w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1892-768x1336.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1892.jpg 828w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/td>\n<td style=\"width: 50%; border-color: #ffffff; background-color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7081 alignleft\" src=\"https:\/\/www.guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1893.jpg\" alt=\"\" width=\"300\" height=\"522\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1893.jpg 828w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1893-300x522.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1893-172x300.jpg 172w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1893-588x1024.jpg 588w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1893-768x1338.jpg 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: center;\"><em>Captures d&#8217;\u00e9crans de mes stories Instagram : <a href=\"https:\/\/www.instagram.com\/guillaumeteillet\/\">@guillaumeteillet<\/a><\/em><\/p>\n<p>Du c\u00f4t\u00e9 du logement en lui-m\u00eame, il est vraiment confortable et propre : la salle de bain est moderne et la cuisine est tr\u00e8s bien \u00e9quip\u00e9e. Pour terminer, la literie est excellente et la connexion internet fonctionne tr\u00e8s bien !<\/p>\n<p>Pour toutes ces raisons, nous recommandons sans h\u00e9siter <a href=\"https:\/\/www.airbnb.fr\/associates\/92455?s=67&amp;c=.pi115.pk0_9&amp;a4ptk=16690_0_9_92455&amp;af=115\">le logement de V\u00e9ronique si vous \u00eates de passage dans les environs de Neaux<\/a> : il vous suffit de cliquer sur l&#8217;annonce ci-dessous :<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_raw_code wpb_content_element wpb_raw_html\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<center><div><script src=\"https:\/\/www.airbnb.fr\/embeddable\/airbnb_jssdk\" async=\"\"><\/script><div class=\"airbnb-embed-frame\" data-view=\"a4p_collection_embeddable\" data-id=\"91368\" data-width=\"562\" style=\"width:562px\"><\/div><\/div><\/center>\n\t\t<\/div>\n\t<\/div>\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>Si vous n\u2019avez pas encore de compte Airbnb,\u00a0<a href=\"https:\/\/www.airbnb.fr\/c\/guillaumet5462?referral_share_id=fc366b71-223d-412d-948e-554d1fdb13bb\">vous pouvez profiter d\u2019une r\u00e9duction de 46 euros sur votre premier s\u00e9jour en vous inscrivant avec ce lien<\/a>.<\/p>\n<p>Comme nous sommes rest\u00e9s peu de temps dans les environs, nous n&#8217;avons aucun lieu ni aucune activit\u00e9 \u00e0 vous recommander pr\u00e8s de Neaux : nous avons profit\u00e9 de ces quelques jours pour nous reposer dans ce airbnb \u00e0 la campagne.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p><em>Cet article contient un ou plusieurs liens d\u2019affiliations : cela signifie que je recevrais une petite commission si vous achetez ce produit (sans que cela n\u2019entra\u00eene un co\u00fbt suppl\u00e9mentaire pour vous).<\/em><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Cet article est le troisi\u00e8me d'une s\u00e9rie 6 articles qui retracent mon roadtrip en France (du 17 Juin au 4 Juillet 2020). Vous pouvez : Lire l'\u00e9pisode 1,\u00a0 Lire l'\u00e9pisode...","protected":false},"author":1,"featured_media":7077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-7037","post","type-post","status-publish","format-standard","has-post-thumbnail","category-voyages"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\ud83d\ude97 Roadtrip en France #3 : Neaux - Guillaume TEILLET<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guillaumeteillet.com\/en\/roadtrip-en-france-neaux\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83d\ude97 Roadtrip en France #3 : Neaux - Guillaume TEILLET\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guillaumeteillet.com\/en\/roadtrip-en-france-neaux\/\" \/>\n<meta property=\"og:site_name\" content=\"Guillaume TEILLET\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-28T08:30:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-23T15:23:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/7e988822-1ceb-4991-84e4-9c7337b18b5a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guillaume Teillet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guillaume Teillet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/\",\"url\":\"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/\",\"name\":\"\ud83d\ude97 Roadtrip en France #3 : Neaux - Guillaume TEILLET\",\"isPartOf\":{\"@id\":\"https:\/\/guillaumeteillet.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/7e988822-1ceb-4991-84e4-9c7337b18b5a.jpg\",\"datePublished\":\"2020-09-28T08:30:01+00:00\",\"dateModified\":\"2020-09-23T15:23:32+00:00\",\"author\":{\"@id\":\"https:\/\/guillaumeteillet.com\/#\/schema\/person\/27fe48f08db74c8dee381b5f2277534f\"},\"breadcrumb\":{\"@id\":\"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/#primaryimage\",\"url\":\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/7e988822-1ceb-4991-84e4-9c7337b18b5a.jpg\",\"contentUrl\":\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/7e988822-1ceb-4991-84e4-9c7337b18b5a.jpg\",\"width\":1440,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\/\/guillaumeteillet.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ud83d\ude97 Roadtrip en France #3 : Neaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/guillaumeteillet.com\/#website\",\"url\":\"https:\/\/guillaumeteillet.com\/\",\"name\":\"Guillaume TEILLET\",\"description\":\"Cr\u00e9er - Entreprendre - Investir - Partager\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/guillaumeteillet.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/guillaumeteillet.com\/#\/schema\/person\/27fe48f08db74c8dee381b5f2277534f\",\"name\":\"Guillaume Teillet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/guillaumeteillet.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9075bedaaadc1fe3829c3f7f40c99480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9075bedaaadc1fe3829c3f7f40c99480?s=96&d=mm&r=g\",\"caption\":\"Guillaume Teillet\"},\"sameAs\":[\"https:\/\/www.guillaumeteillet.com\"],\"url\":\"https:\/\/guillaumeteillet.com\/en\/author\/guillaume-teillet\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83d\ude97 Roadtrip en France #3 : Neaux - Guillaume TEILLET","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guillaumeteillet.com\/en\/roadtrip-en-france-neaux\/","og_locale":"en_US","og_type":"article","og_title":"\ud83d\ude97 Roadtrip en France #3 : Neaux - Guillaume TEILLET","og_url":"https:\/\/guillaumeteillet.com\/en\/roadtrip-en-france-neaux\/","og_site_name":"Guillaume TEILLET","article_published_time":"2020-09-28T08:30:01+00:00","article_modified_time":"2020-09-23T15:23:32+00:00","og_image":[{"width":1440,"height":960,"url":"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/7e988822-1ceb-4991-84e4-9c7337b18b5a.jpg","type":"image\/jpeg"}],"author":"Guillaume Teillet","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Guillaume Teillet","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/","url":"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/","name":"\ud83d\ude97 Roadtrip en France #3 : Neaux - Guillaume TEILLET","isPartOf":{"@id":"https:\/\/guillaumeteillet.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/#primaryimage"},"image":{"@id":"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/#primaryimage"},"thumbnailUrl":"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/7e988822-1ceb-4991-84e4-9c7337b18b5a.jpg","datePublished":"2020-09-28T08:30:01+00:00","dateModified":"2020-09-23T15:23:32+00:00","author":{"@id":"https:\/\/guillaumeteillet.com\/#\/schema\/person\/27fe48f08db74c8dee381b5f2277534f"},"breadcrumb":{"@id":"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/#primaryimage","url":"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/7e988822-1ceb-4991-84e4-9c7337b18b5a.jpg","contentUrl":"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/7e988822-1ceb-4991-84e4-9c7337b18b5a.jpg","width":1440,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/guillaumeteillet.com\/roadtrip-en-france-neaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/guillaumeteillet.com\/"},{"@type":"ListItem","position":2,"name":"\ud83d\ude97 Roadtrip en France #3 : Neaux"}]},{"@type":"WebSite","@id":"https:\/\/guillaumeteillet.com\/#website","url":"https:\/\/guillaumeteillet.com\/","name":"Guillaume TEILLET","description":"Cr\u00e9er - Entreprendre - Investir - Partager","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guillaumeteillet.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/guillaumeteillet.com\/#\/schema\/person\/27fe48f08db74c8dee381b5f2277534f","name":"Guillaume Teillet","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/guillaumeteillet.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9075bedaaadc1fe3829c3f7f40c99480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9075bedaaadc1fe3829c3f7f40c99480?s=96&d=mm&r=g","caption":"Guillaume Teillet"},"sameAs":["https:\/\/www.guillaumeteillet.com"],"url":"https:\/\/guillaumeteillet.com\/en\/author\/guillaume-teillet\/"}]}},"_links":{"self":[{"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/posts\/7037"}],"collection":[{"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/comments?post=7037"}],"version-history":[{"count":16,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/posts\/7037\/revisions"}],"predecessor-version":[{"id":7093,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/posts\/7037\/revisions\/7093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/media\/7077"}],"wp:attachment":[{"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/media?parent=7037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/categories?post=7037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/tags?post=7037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}