{"id":7114,"date":"2021-02-08T08:00:52","date_gmt":"2021-02-08T07:00:52","guid":{"rendered":"https:\/\/www.guillaumeteillet.com\/?p=7114"},"modified":"2021-02-01T23:08:45","modified_gmt":"2021-02-01T22:08:45","slug":"ma-vie-en-ukraine","status":"publish","type":"post","link":"https:\/\/guillaumeteillet.com\/en\/ma-vie-en-ukraine\/","title":{"rendered":"\ud83c\uddfa\ud83c\udde6 Ma vie en Ukraine"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 14<\/span> <span class=\"rt-label rt-postfix\">minutes<br \/><br \/><\/span><\/span>\n\t\t<div id=\"fws_6a046671baf0c\"  data-column-margin=\"default\" data-midnight=\"dark\"  data-bg-mobile-hidden=\"\" class=\"wpb_row vc_row-fluid vc_row standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay\" ><\/div><\/div><div class=\"col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding\"  data-t-w-inherits=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-border-animation=\"\" data-border-animation-delay=\"\" data-border-width=\"none\" data-border-style=\"solid\" data-border-color=\"\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p><em>Dans cet article, je vais vous parler des trois mois que j&#8217;ai pass\u00e9 en Ukraine : fin Ao\u00fbt 2020, je me suis install\u00e9 \u00e0 Lviv en Ukraine afin de d\u00e9couvrir le pays et d&#8217;effectuer des recherches g\u00e9n\u00e9alogiques.<\/em><\/p>\n<p><em>Je n\u2019ai pas la pr\u00e9tention de conna\u00eetre ce pays suffisamment pour \u00e9crire un article aussi d\u00e9taill\u00e9 que celui sur la\u00a0<a href=\"https:\/\/guillaumeteillet.com\/en\/mon-annee-en-chine\/\">Chine<\/a>,\u00a0<a href=\"https:\/\/guillaumeteillet.com\/en\/ma-vie-a-singapour\/\">Singapour<\/a>\u00a0ou\u00a0<a href=\"https:\/\/guillaumeteillet.com\/en\/decouverte-de-hong-kong\/\">Hong Kong<\/a>\u00a0mais je pense que vous y trouverez quand m\u00eame quelques informations !<\/em><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>I \u2013 Introduction<\/h2>\n<p>Apr\u00e8s avoir <a href=\"https:\/\/guillaumeteillet.com\/en\/on-repart-a-letranger-decouverte-de-la-croatie\/\">pass\u00e9 pr\u00e8s de 2 mois en Croatie<\/a>, nous avons mis le cap sur l&#8217;Ukraine : nous sommes arriv\u00e9s \u00e0 Lviv le 22 Ao\u00fbt 2020.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1424.png\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"4032\" width=\"3024\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1424.png\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1424.png 3024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1424-300x400.png 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1424-225x300.png 225w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1424-768x1024.png 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1424-1152x1536.png 1152w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1424-1536x2048.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Arriv\u00e9e \u00e0 l&#8217;a\u00e9roport de Lviv, Ukraine<\/em><\/p>\n<p>Dans cet article, je me d\u00e9voile un peu plus que d&#8217;habitude et je ne vais pas uniquement parler de mon voyage : je vais vous expliquer comment j&#8217;ai d\u00e9couvert que ma famille avait un lien avec ce pays et comment j&#8217;y ai retrouv\u00e9 une partie de ma famille avec qui nous avions perdu tout contact depuis 88 ans.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>II \u2013 Quelques mots sur une partie de mon histoire familiale&#8230;<\/h2>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 52px; top: 51.9062px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>Lorsque j&#8217;\u00e9tais enfant, j&#8217;ai essay\u00e9 \u00e0 plusieurs reprises de rechercher des informations sur mes anc\u00eatres afin d&#8217;\u00e9tablir mon arbre g\u00e9n\u00e9alogique : malheureusement, toutes mes tentatives se sold\u00e8rent tr\u00e8s vite par des \u00e9checs\u00a0 par manque d&#8217;outils et d&#8217;acc\u00e8s aux diff\u00e9rentes archives.<\/p>\n<p>En D\u00e9cembre 2018, alors que nous \u00e9tions \u00e0 Sydney en Australie, ma compagne \u00e0 commenc\u00e9 a faire des recherches sur ses anc\u00eatres : petit \u00e0 petit, j&#8217;ai d\u00e9couvert que de nouveaux outils en lignes permettaient de faire des recherches et que les archives commen\u00e7aient \u00e0 \u00eatre num\u00e9ris\u00e9es. Je me suis de nouveau int\u00e9ress\u00e9 \u00e0 la g\u00e9n\u00e9alogie et j&#8217;ai commenc\u00e9 \u00e0 faire mes propres recherches.<\/p>\n<p>Je me suis int\u00e9ress\u00e9 \u00e0 mon c\u00f4t\u00e9 maternel : mon arri\u00e8re-grand-p\u00e8re \u00e9tait polonais. D&#8217;apr\u00e8s l&#8217;histoire familiale, il \u00e9tait arriv\u00e9 en France lorsqu&#8217;il \u00e9tait jeune pour travailler dans les mines de charbon du nord de la France. Il avait rencontr\u00e9 sa femme, mon arri\u00e8re-grand-m\u00e8re, \u00e0 Douai o\u00f9 ils se sont mari\u00e9s et o\u00f9 ils ont fond\u00e9 une famille de 10 enfants.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class='twentytwenty-container'>\r\n  <img class='skip-lazy' src='https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/Photo6500988.jpg' alt=''>\r\n  <img class='skip-lazy' src='https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/Photo6500988-Colorized.jpg' alt=''>\r\n<\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><i>Mon arri\u00e8re-grand-p\u00e8re, Michel BOBA<\/i><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 307px; top: -10px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>L&#8217;un de mes premiers objectifs a \u00e9t\u00e9 d&#8217;\u00e9tablir avec certitude son lieu de naissance. Je savais que mon arri\u00e8re-grand-p\u00e8re \u00e9tait rest\u00e9 polonais toute sa vie et qu&#8217;il ne s&#8217;est jamais fait naturalis\u00e9 Fran\u00e7ais. Par cons\u00e9quent, je ne pouvais pas m&#8217;appuyer sur un dossier de naturalisation pour avancer dans mes recherches.<\/p>\n<p>En revanche, j&#8217;ai r\u00e9ussi \u00e0 obtenir plusieurs documents d&#8217;identit\u00e9 lui ayant appartenu : sa derni\u00e8re carte de r\u00e9sident, son acte de mariage, son dossier d&#8217;employ\u00e9 et enfin, son acte de d\u00e9c\u00e8s. Malheureusement, chaque document indiquait un lieu de naissance diff\u00e9rent, ou plut\u00f4t, avec une orthographe diff\u00e9rente : Lipawa, Lipowa, Lipowce, Lipowice ou encore Lypivtsi.<\/p>\n<p>Heureusement, gr\u00e2ce \u00e0 un document militaire que j&#8217;ai obtenu des archives f\u00e9d\u00e9rales suisses, j&#8217;ai pu \u00e9tablir que son lieu de naissance se trouvait dans la r\u00e9gion de Lw\u00f3w. Apr\u00e8s quelques recherches, je me suis aper\u00e7u que la ville polonaise de Lw\u00f3w \u00e9tait devenue la ville ukrainienne de Lviv et qu&#8217;il fallait que je concentre mes recherches sur l&#8217;Ukraine et non pas la Pologne : en effet, \u00e0 la fin de la Seconde Guerre mondiale, la r\u00e9gion de Lviv a \u00e9t\u00e9 annex\u00e9e par la R\u00e9publique socialiste sovi\u00e9tique d&#8217;Ukraine.<\/p>\n<p>En Novembre 2019, que ma compagne et moi avons pris la d\u00e9cision de nous rendre \u00e0 Lviv en Ukraine au mois de Mars 2020 pour quelques mois afin de faire des recherches sur le terrain.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>III \u2013 Comment j&#8217;ai r\u00e9uni ma famille apr\u00e8s 88 ans de s\u00e9paration<\/h2>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>Gr\u00e2ce \u00e0 ma grand-m\u00e8re, j&#8217;ai su tr\u00e8s rapidement que mon arri\u00e8re-grand-p\u00e8re avait un grand fr\u00e8re et une demi-soeur. L&#8217;un de mes oncles se souvenait du nom de cette demi-soeur : Stanislawa &#8220;Stacha&#8221; OSESEK. Gr\u00e2ce \u00e0 son aide, j&#8217;ai pu retrouver le cimeti\u00e8re o\u00f9 elle repose avec son p\u00e8re, Joseph OSESEK, le beau-p\u00e8re de mon arri\u00e8re-grand-p\u00e8re et de son fr\u00e8re.<\/p>\n<p>J&#8217;ai pu \u00e9tablir avec certitude que Stanislawa \u00e9tait n\u00e9 en France et que par cons\u00e9quent, la m\u00e8re de mon arri\u00e8re-grand-p\u00e8re, Caroline MEDYNSKY, avait du venir en France avec son second mari, Joseph OSESEK, et mon arri\u00e8re-grand-p\u00e8re, Michel. J&#8217;ai appris plus tard que Caroline MEDYNSKY \u00e9tait enterr\u00e9e dans une tombe anonyme dans le m\u00eame cimeti\u00e8re que mon arri\u00e8re-grand-p\u00e8re : \u00e0 Douai, en France.<\/p>\n<p>En revanche, pendant longtemps mes recherches sur le grand fr\u00e8re de mon arri\u00e8re-grand-p\u00e8re n&#8217;ont rien donn\u00e9 : aucun des enfants de mon arri\u00e8re-grand-p\u00e8re ne se souvenait de l&#8217;avoir rencontr\u00e9 et personne ne connaissait son nom, car \u00e0 l&#8217;\u00e9poque, &#8220;on ne parlait pas beaucoup du pass\u00e9&#8221;.<\/p>\n<p>En revanche, gr\u00e2ce \u00e0 la fille a\u00een\u00e9e de mon arri\u00e8re-grand-p\u00e8re, j&#8217;ai r\u00e9ussi \u00e0 mettre la main sur cette photo d&#8217;\u00e9poque :<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class='twentytwenty-container'>\r\n  <img class='skip-lazy' src='https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_8288-scaled.jpg' alt=''>\r\n  <img class='skip-lazy' src='https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/Photo6501317-Colorized-scaled.jpg' alt=''>\r\n<\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><i>Mon arri\u00e8re-grand-p\u00e8re (\u00e0 gauche) et son fr\u00e8re (\u00e0 droite).<br \/>\n<\/i><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 549px; top: 38px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>En analysant cette photo, je me suis aper\u00e7u qu&#8217;elle comportait le nom de la ville o\u00f9 elle a \u00e9t\u00e9 prise : Waziers. Il s&#8217;agit d&#8217;une commune voisine de Douai : j&#8217;en ai donc conclu que si cette photo avait \u00e9t\u00e9 prise en France, le fr\u00e8re de mon arri\u00e8re-grand-p\u00e8re avait d\u00fb lui aussi venir en France avec sa m\u00e8re Caroline, son fr\u00e8re Michel et son beau-p\u00e8re Joseph.<\/p>\n<p>Il est probable que Joseph OSESEK soit venu en France pour travailler dans les mines de charbon, comme beaucoup de Polonais \u00e0 l&#8217;\u00e9poque, et peut-\u00eatre que le grand fr\u00e8re de Michel travaillait lui aussi dans les mines du nord de la France.<\/p>\n<p>Apr\u00e8s mes 3 mois en Australie, j&#8217;ai pris un avion pour Lille afin de consulter diff\u00e9rents fonds d&#8217;archive de la r\u00e9gion et essay\u00e9 de retrouver la trace de ces deux fr\u00e8res dans des documents. Apr\u00e8s quelques recherches, j&#8217;ai r\u00e9ussi \u00e0 r\u00e9cup\u00e9rer le dossier d&#8217;employ\u00e9 des mines de mon arri\u00e8re-grand-p\u00e8re mais malheureusement, il n&#8217;existait aucun autre dossier portant le nom de BOBA.<\/p>\n<p>Pourtant, la photo des deux fr\u00e8res prouvait bien que son fr\u00e8re \u00e9tait venu en France : je me suis donc rendu aux archives de la ville de Lille afin de consulter les registres des demandes de cartes d&#8217;identit\u00e9 des \u00e9trangers pour la p\u00e9riode qui m&#8217;int\u00e9ressait (entre 1915 et aujourd&#8217;hui). \u00c0 cette \u00e9poque, chaque \u00e9tranger en France devait renouveler sa carte d&#8217;identit\u00e9 aupr\u00e8s du commissariat de police.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2185.png\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"4032\" width=\"3024\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2185.png\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2185.png 3024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2185-300x400.png 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2185-225x300.png 225w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2185-768x1024.png 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2185-1152x1536.png 1152w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2185-1536x2048.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><i>Consultation des archives de Lille<br \/>\n<\/i><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>Gr\u00e2ce \u00e0 ses registres, j&#8217;ai d\u00e9couvert le pr\u00e9nom du fr\u00e8re de mon arri\u00e8re-grand-p\u00e8re : Joseph ! En effet, un Joseph BOBA avait demand\u00e9 une carte d&#8217;identit\u00e9 et il habitait&#8230; \u00e0 la m\u00eame adresse que mon arri\u00e8re-grand-p\u00e8re !<\/p>\n<p>Munis de cette nouvelle information et pour pr\u00e9parer notre voyage en Ukraine, nous avons fait appel \u00e0 Viktor, un g\u00e9n\u00e9alogiste expert de la r\u00e9gion : gr\u00e2ce \u00e0 son travail de terrain, Viktor a pu m&#8217;aider \u00e0 confirmer que Lypivtsi \u00e9tait bel et bien le village de naissance de mon arri\u00e8re-grand-p\u00e8re et, \u00e0 ma grande surprise, il a m\u00eame retrouv\u00e9 la maison familiale o\u00f9 il est n\u00e9, ainsi que des descendants de son fr\u00e8re Joseph !<\/p>\n<p>C&#8217;est ainsi qu&#8217;en F\u00e9vrier 2020 je suis rentr\u00e9 en contact avec Nadyia BOBA, la petite fille de Joseph BOBA : elle est Ukrainienne et vit \u00e0 Peremychliany, une petite ville qui se situe \u00e0 10 km de Lypivtsi.<\/p>\n<p>Gr\u00e2ce \u00e0 l&#8217;aide de Nadyia, j&#8217;ai pu en apprendre plus sur le fr\u00e8re de mon arri\u00e8re-grand-p\u00e8re et ses parents : le p\u00e8re de Michel et Joseph, Nicolas BOBA, est d\u00e9c\u00e9d\u00e9 lors d&#8217;une guerre. Sa femme, Caroline s&#8217;est remari\u00e9e avec Joseph OSESEK et elle est partie pour la France en Mai 1926 avec ses deux fils.<\/p>\n<p>En 1929, Caroline accoucha de Stanislawa, la demi-soeur des deux fr\u00e8res. Malheureusement, Caroline d\u00e9c\u00e9da en 1932 \u00e0 l&#8217;\u00e2ge de 42 ans. C&#8217;est cet \u00e9v\u00e8nement qui changea le cours des choses :<\/p>\n<ul>\n<li>Joseph d\u00e9cida de quitter la France pour rentrer \u00e0 Lypivtsi o\u00f9 il se maria et fondera une famille quelques ann\u00e9es plus tard,<\/li>\n<li>Stanislawa fut \u00e9lev\u00e9 par son p\u00e8re et d\u00e9c\u00e9da \u00e0 l&#8217;\u00e2ge de 47 ans sans laisser de descendance,<\/li>\n<li>et Michel resta en France, \u00e0 Douai, o\u00f9 il fonda sa famille.<\/li>\n<\/ul>\n<p>Stanislawa reprit contact avec Michel plusieurs ann\u00e9es plus tard. Ce ne fut pas le cas de Joseph : \u00e0 l&#8217;\u00e9poque, pas d&#8217;Internet, ni m\u00eame de service postal digne de ce nom entre les deux pays.<\/p>\n<p>Apr\u00e8s 88 ans de s\u00e9paration, j&#8217;ai donc retrouv\u00e9 cette partie de ma famille et j&#8217;ai renou\u00e9 des liens : s\u00e9par\u00e9s par le temps, la distance, la guerre et m\u00eame le COVID (mon voyage pr\u00e9vu en Mars a \u00e9t\u00e9 repouss\u00e9 en Juillet 2020&#8230;) mais r\u00e9unis gr\u00e2ce \u00e0 mes recherches et \u00e0 mon obstination.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class='twentytwenty-container'>\r\n  <img class='skip-lazy' src='https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/Photo6501095-e1611599866344.jpg' alt=''>\r\n  <img class='skip-lazy' src='https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/Photo6501095-Colorized-e1611599880267.jpg' alt=''>\r\n<\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><i>Mon arri\u00e8re-grand-p\u00e8re (en haut, \u00e0 gauche), son fr\u00e8re, Joseph BOBA (en haut, \u00e0 droite).<br \/>\nLeur beau-p\u00e8re, Joseph OSESEK (assis) et leur demi-soeur, Stanislawa OSESEK (sur les genoux)<\/i><\/p>\n<p>Lorsque j&#8217;ai rencontr\u00e9 Nadyia \u00e0 Lviv elle m&#8217;a remis la photo ci-dessus : elle savait que son grand-p\u00e8re avait un fr\u00e8re et une soeur, mais elle ne connaissait pas leurs pr\u00e9noms.<\/p>\n<p>Nadyia m&#8217;a \u00e9galement pr\u00e9sent\u00e9 aux autres membres de ma famille Ukrainienne (au total 4 enfants, 8 petits-enfants, 17 arri\u00e8res-petits-enfants et 2 arri\u00e8res-arri\u00e8res-petits-enfants&#8230;) : m\u00eame avec la barri\u00e8re de la langue, nous avons r\u00e9ussi \u00e0 \u00e9changer et \u00e0 nous comprendre, vive la technologie !<\/p>\n<p>Nadyia a \u00e9galement retrouv\u00e9 de tr\u00e8s vieilles photos de famille : gr\u00e2ce \u00e0 l&#8217;aide d&#8217;une descendante de la famille MEDYNSKI, nous avons pu confirmer que les personnes pr\u00e9sentes sur ces photos \u00e9taient les parents de Michel et Joseph : Caroline MEDYNSKI et Nicolas BOBA.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class='twentytwenty-container'>\r\n  <img class='skip-lazy' src='https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3189-e1611600513191.png' alt=''>\r\n  <img class='skip-lazy' src='https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/Photo6501313-Color-Restored-scaled-e1611600557197.jpg' alt=''>\r\n<\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><i>\u00c0 gauche, mon arri\u00e8re-arri\u00e8re-grand-m\u00e8re, Caroline Medynski<\/i><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class='twentytwenty-container'>\r\n  <img class='skip-lazy' src='https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3192.png' alt=''>\r\n  <img class='skip-lazy' src='https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/Photo6501315-Colorized.jpg' alt=''>\r\n<\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><i>En haut, 3 \u00e8me \u00e0 partir de la droite : mon arri\u00e8re-arri\u00e8re-grand-p\u00e8re, Nicolas BOBA<\/i><\/p>\n<p>Sur cette derni\u00e8re photo, prise tr\u00e8s certainement au d\u00e9but des ann\u00e9es 1900 , mon arri\u00e8re-arri\u00e8re-grand-p\u00e8re est entour\u00e9 d&#8217;un tr\u00e8s grand nombre de personnes : malheureusement, il est possible que tous ces visages restent anonymes pour toujours car la photo n&#8217;est pas annot\u00e9e et personne n&#8217;est en mesure de les reconna\u00eetre.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>IV \u2013 Dans les pas de mes anc\u00eatres&#8230;<\/h2>\n<p>Gr\u00e2ce \u00e0 Yaroslav et Nadyia, mes cousins ukrainiens, j&#8217;ai pu me rendre dans le village de naissance de mon arri\u00e8re-grand-p\u00e8re.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-scaled.jpg\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1920\" width=\"2560\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-scaled.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-scaled.jpg 2560w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-300x225.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-1024x768.jpg 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-768x576.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-1536x1152.jpg 1536w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-2048x1536.jpg 2048w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Moi devant le panneau du village de Lypivtsi<\/em><\/p>\n<p>C&#8217;est un village difficile d&#8217;acc\u00e8s : la route qui y conduit n&#8217;a pas \u00e9t\u00e9 r\u00e9nov\u00e9e depuis tr\u00e8s longtemps et il est impossible d&#8217;avoir du r\u00e9seau sur place.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1650.png\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"3024\" width=\"4032\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1650.png\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1650.png 4032w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1650-300x225.png 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1650-1024x768.png 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1650-768x576.png 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1650-1536x1152.png 1536w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1650-2048x1536.png 2048w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>En route pour le village de naissance de mon arri\u00e8re-grand-p\u00e8re<\/em><\/p>\n<p>Heureusement, Yaroslav est venu me chercher \u00e0 Lviv et il m&#8217;a conduit jusqu&#8217;\u00e0 la maison de Caroline et Nicolas BOBA, mes arri\u00e8res-arri\u00e8res-grands-parents : c&#8217;est dans cette maison que sont n\u00e9 Joseph et Michel.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items masonry-items\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1714-600x400.png\" width=\"600\" height=\"400\" alt=\"La maison de naissance de mon arri\u00e8re-grand-p\u00e8re\" title=\"La maison de naissance de mon arri\u00e8re-grand-p\u00e8re\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1714.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1729-600x400.png\" width=\"600\" height=\"400\" alt=\"La maison de naissance de mon arri\u00e8re-grand-p\u00e8re\" title=\"La maison de naissance de mon arri\u00e8re-grand-p\u00e8re\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1729.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1725-600x400.png\" width=\"600\" height=\"400\" alt=\"La maison de naissance de mon arri\u00e8re-grand-p\u00e8re\" title=\"La maison de naissance de mon arri\u00e8re-grand-p\u00e8re\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1725.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>La maison de naissance de mon arri\u00e8re-grand-p\u00e8re<\/em><\/p>\n<p>En 1926, quand Caroline est partie en France avec ses enfants, la maison a \u00e9t\u00e9 laiss\u00e9e \u00e0 l&#8217;abandon pendant plusieurs ann\u00e9es.<\/p>\n<p>Apr\u00e8s le d\u00e9c\u00e8s de sa m\u00e8re, Joseph est revenu s&#8217;installer \u00e0 Lypivtsi : il a habit\u00e9 pendant quelque temps dans cette maison, avant de construire sa propre maison (aujourd&#8217;hui en ruine) \u00e0 quelques m\u00e8tres de celle-ci.<\/p>\n<p>Lorsque les Sovi\u00e9tiques sont arriv\u00e9s, ils ont confisqu\u00e9 les terrains agricoles et la maison appartenant \u00e0 la famille BOBA. \u00c0 la fin de l&#8217;Union sovi\u00e9tique, la mairie du village d\u00e9cida de transformer la maison en h\u00f4pital de campagne, puis en logement social. Aujourd&#8217;hui encore, la maison est habit\u00e9e par une famille modeste.<\/p>\n<p>\u00c0 quelques minutes de voiture de Lypivtsi, il y avait un deuxi\u00e8me village que je souhaitais visiter : le village de naissance de Caroline, mon arri\u00e8re-arri\u00e8re-grand-m\u00e8re.<\/p>\n<p>Yaroslav m&#8217;a donc conduit \u00e0 Plenykiv, un village encore plus isol\u00e9 que Lypivtsi. Sur place, j&#8217;ai pu faire quelques recherches dans le cimeti\u00e8re et admirer l&#8217;ancienne \u00e9glise polonaise du village qui est aujourd&#8217;hui en ruine.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items masonry-items\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1742-600x400.png\" width=\"600\" height=\"400\" alt=\"Le village de mon arri\u00e8re-arri\u00e8re-grand-m\u00e8re\" title=\"Le village de mon arri\u00e8re-arri\u00e8re-grand-m\u00e8re\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1742.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1752-600x400.png\" width=\"600\" height=\"400\" alt=\"Ancienne \u00e9glise polonaise\" title=\"Ancienne \u00e9glise polonaise\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1752.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1829-600x400.png\" width=\"600\" height=\"400\" alt=\"Le village de mon arri\u00e8re-arri\u00e8re-grand-m\u00e8re\" title=\"Le village de mon arri\u00e8re-arri\u00e8re-grand-m\u00e8re\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1829.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Visite du village de naissance de mon arri\u00e8re-arri\u00e8re-grand-m\u00e8re : Plenykiv<\/em><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>V \u2013 Lviv, notre camp de base<\/h2>\n<p>Pour faire toutes ses recherches et pour rentrer en contact avec mes cousins, nous avons \u00e9tabli notre camp de base pour 3 mois \u00e0 Lviv, une ville de l&#8217;ouest de l&#8217;Ukraine qui se situe \u00e0 seulement 70 km de la fronti\u00e8re avec la Pologne.<\/p>\n<p>Nous avons lou\u00e9 un Airbnb au nord de Lviv dans un quartier r\u00e9sidentiel tr\u00e8s calme :<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_raw_code wpb_content_element wpb_raw_html\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<center><div><script src=\"https:\/\/www.airbnb.fr\/embeddable\/airbnb_jssdk\" async=\"\"><\/script><div class=\"airbnb-embed-frame\" data-view=\"a4p_collection_embeddable\" data-id=\"383362\" data-width=\"562\" style=\"width:562px\"><\/div><\/div><\/center>\n\t\t<\/div>\n\t<\/div>\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>Nous avons ador\u00e9 Lviv qui est une ville tr\u00e8s agr\u00e9able et o\u00f9 il fait bon vivre. Voici quelque unes de nos recommandations :<\/p>\n<ul>\n<li><strong>Gwara Delicatessen :<\/strong> Un tr\u00e8s bon restaurant Ukrainien dans la vieille ville de Lviv. Je vous conseille de d\u00e9couvrir les <em>Varenyky<\/em> : ce sont des raviolis ukrainiens.<\/li>\n<\/ul>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1500.png\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"3024\" width=\"4032\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1500.png\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1500.png 4032w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1500-300x225.png 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1500-1024x768.png 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1500-768x576.png 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1500-1536x1152.png 1536w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1500-2048x1536.png 2048w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Les raviolis Ukrainiens de Gwara Delicatessen<\/em><\/p>\n<ul>\n<li><strong>Lviv Coffee Manufacture :<\/strong> il s&#8217;agit d&#8217;un caf\u00e9 situ\u00e9 sur la place centrale de Lviv, la place Rynok. Ce caf\u00e9 est sp\u00e9cial pour plusieurs raisons : la salle est tr\u00e8s belle, ils ont \u00e9galement une v\u00e9randa tr\u00e8s lumineuse et au sous-sol, ils vous servent le caf\u00e9 dans une ambiance tamis\u00e9 et il le chauffe en utilisant un chalumeau : un spectacle incroyable !<\/li>\n<\/ul>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_142225-scaled.jpg\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1920\" width=\"2560\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_142225-scaled.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_142225-scaled.jpg 2560w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_142225-300x225.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_142225-1024x768.jpg 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_142225-768x576.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_142225-1536x1152.jpg 1536w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_142225-2048x1536.jpg 2048w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>La v\u00e9randa de Lviv Coffee Manufacture\u00a0<\/em><\/p>\n<ul>\n<li><strong>Kryivka :<\/strong> L&#8217;un des restaurants Ukrainien les plus secrets de Lviv ! Comme de nombreux restaurants \u00e0 Lviv, il est \u00e0 th\u00e8me : le th\u00e8me de celui-ci est la guerre et l&#8217;arm\u00e9e Ukrainienne. Il est aussi situ\u00e9 sur la place Rynok mais il est plus difficile \u00e0 trouver si vous ne le connaissez pas.<\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\">Entrez num\u00e9ro 14 et vous devriez voir au bout du couloir une porte en bois avec une petite fen\u00eatre : tapez et attendez que le soldat ouvre la fen\u00eatre. Vous devrez alors lui donner le mot de passe pour entrer : &#8220;Slava Ukraina&#8221; qui signifie &#8220;Gloire \u00e0 l&#8217;Ukraine&#8221;. Il ouvrira alors la porte, vous servira un vrai d&#8217;alcool, puis vous laissera entrer dans le restaurant.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201108_132550-scaled.jpg\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1920\" width=\"2560\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201108_132550-scaled.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201108_132550-scaled.jpg 2560w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201108_132550-300x225.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201108_132550-1024x768.jpg 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201108_132550-768x576.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201108_132550-1536x1152.jpg 1536w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201108_132550-2048x1536.jpg 2048w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Kryivka : Le restaurant o\u00f9 il vous faudra un mot de passe pour rentrer !<\/em><\/p>\n<ul>\n<li><strong>Fifth Dungeon :<\/strong> toujours sur la place Rynok, un autre restaurant mais celui-ci \u00e0 pour th\u00e8me le Moyen-\u00e2ge ! Les serveurs sont en costume et l&#8217;ambiance est tr\u00e8s sympa !<\/li>\n<\/ul>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_135532-scaled.jpg\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"2560\" width=\"1920\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_135532-scaled.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_135532-scaled.jpg 1920w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_135532-scaled-300x400.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_135532-225x300.jpg 225w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_135532-768x1024.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_135532-1152x1536.jpg 1152w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201106_135532-1536x2048.jpg 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Le restaurant M\u00e9di\u00e9val Fifth Dungeon<\/em><\/p>\n<ul>\n<li><strong>Le Centre Culturel de la Bi\u00e8re Lvivarnya :<\/strong> il s&#8217;agit d&#8217;un mus\u00e9e sur la bi\u00e8re locale Lvivarnya. \u00c0 la fin de la visite, vous pourrez tester 4 bi\u00e8res diff\u00e9rentes pour quelques euros.<\/li>\n<\/ul>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201109_163030-scaled.jpg\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1920\" width=\"2560\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201109_163030-scaled.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201109_163030-scaled.jpg 2560w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201109_163030-300x225.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201109_163030-1024x768.jpg 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201109_163030-768x576.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201109_163030-1536x1152.jpg 1536w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_20201109_163030-2048x1536.jpg 2048w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Le centre culturel de la bi\u00e8re Lvivarnya<\/em><\/p>\n<ul>\n<li><strong>Restaurant Gas Lamp :<\/strong> Un autre restaurant \u00e0 th\u00e8me \u00e0 proximit\u00e9 de la place Rynok : celui-ci a pour th\u00e8me la lampe \u00e0 gaz. C&#8217;est un restaurant sur plusieurs \u00e9tages avec une v\u00e9randa au sommet.<\/li>\n<\/ul>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3263.png\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"4032\" width=\"3024\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3263.png\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3263.png 3024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3263-300x400.png 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3263-225x300.png 225w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3263-768x1024.png 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3263-1152x1536.png 1152w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3263-1536x2048.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Le restaurant &#8220;Lampe \u00e0 gaz&#8221;<\/em><\/p>\n<ul>\n<li><strong>Op\u00e9ra de Lviv :<\/strong> construit entre 1897 et 1900, il s&#8217;agit d&#8217;un monument magnifique aussi bien \u00e0 l&#8217;ext\u00e9rieur qu&#8217;\u00e0 l&#8217;int\u00e9rieur.<\/li>\n<\/ul>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3015.png\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"4032\" width=\"3024\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3015.png\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3015.png 3024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3015-300x400.png 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3015-225x300.png 225w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3015-768x1024.png 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3015-1152x1536.png 1152w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_3015-1536x2048.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><i>L&#8217;op\u00e9ra de Lviv<\/i><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 550px; top: -10px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items masonry-items\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 tall element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1626-600x400.png\" width=\"600\" height=\"400\" alt=\"IMG_1626\" title=\"IMG_1626\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1626.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 tall element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1543-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"IMG_1543\" title=\"IMG_1543\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1543-scaled.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 tall element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1454-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"IMG_1454\" title=\"IMG_1454\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1454-scaled.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 tall element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1606-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"IMG_1606\" title=\"IMG_1606\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1606-scaled.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 tall element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1528-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"IMG_1528\" title=\"IMG_1528\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1528-scaled.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 tall element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1525-scaled-600x400.jpg\" width=\"600\" height=\"400\" alt=\"IMG_1525\" title=\"IMG_1525\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_1525-scaled.jpg\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><i>Mon album photo de Lviv<\/i><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 268px; top: -10px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>VI \u2013 Kharkiv : l&#8217;ancienne capitale<\/h2>\n<p>Au mois de Septembre, nous avons pris un train de nuit pour traverser l&#8217;Ukraine d&#8217;Ouest en Est pour nous rendre \u00e0 Kharkiv.<\/p>\n<p>C&#8217;\u00e9tait la premi\u00e8re fois que nous prenions un train de nuit et nous avons \u00e9t\u00e9 agr\u00e9ablement surpris.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2015-scaled.jpg\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1920\" width=\"2560\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2015-scaled.jpg\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2015-scaled.jpg 2560w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2015-300x225.jpg 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2015-1024x768.jpg 1024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2015-768x576.jpg 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2015-1536x1152.jpg 1536w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2015-2048x1536.jpg 2048w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Notre train de nuit pour Kharkiv<\/em><\/p>\n<p>Pour 50 euros par personne, nous avons r\u00e9serv\u00e9 un compartiment pour deux personnes (c&#8217;est la classe la plus luxueuse propos\u00e9e : SW (\u0421\u0412) \u2013 1\u00e8re classe).<\/p>\n<p>Il existe plusieurs autres classes :<\/p>\n<ul>\n<li>un compartiment pour 4 personnes (Coupe \u2013 2nd classe),<\/li>\n<li>un wagon dortoir avec r\u00e9servation (Platzkart \u2013 3\u00e8me classe),<\/li>\n<li>un wagon dortoir sans r\u00e9servation (Common \u2013 4\u00e8me classe)<\/li>\n<li>et enfin, un wagon avec des si\u00e8ges (Seater)<\/li>\n<\/ul>\n<p>Notre compartiment se composait de deux banquettes converties en lit avec des draps : nous avons trouv\u00e9 le sommeil assez rapidement, berc\u00e9 par les mouvements du train.<\/p>\n<p>Vous pouvez fermer la porte de votre compartiment et vous endormir en toute s\u00e9curit\u00e9 : l&#8217;intendant du wagon se charge de vous r\u00e9veiller lorsque vous approchez de votre destination.<\/p>\n<p>En revanche, ne comptez pas sur Internet durant votre voyage : il n&#8217;y a pas de Wifi dans le train et en dehors des villes, vous n&#8217;aurez pas de r\u00e9seau mobile.<\/p>\n<p>Dans la plupart des trains, il n&#8217;y a pas de service de restauration : n&#8217;oubliez pas de faire des provisions !<\/p>\n<p>Nous sommes arriv\u00e9s \u00e0 la gare de Kharkiv vers 11h du matin et nous avons tout de suite \u00e9t\u00e9 frapp\u00e9s par l\u2019esth\u00e9tique de cette gare : reconstruite apr\u00e8s la Seconde Guerre mondiale (\u00e0 l\u2019\u00e9poque sovi\u00e9tique donc), l\u2019architecture de cette gare est de style imp\u00e9rial stalinien.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items masonry-items\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2032-600x400.png\" width=\"600\" height=\"400\" alt=\"La gare ferroviaire de Kharkiv\" title=\"La gare ferroviaire de Kharkiv\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2032.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2074-600x400.png\" width=\"600\" height=\"400\" alt=\"Kharkiv\" title=\"Kharkiv\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2074.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2050-600x400.png\" width=\"600\" height=\"400\" alt=\"Une grande roue a Kharkiv\" title=\"Une grande roue a Kharkiv\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2050.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>La gare ferroviaire de Kharkiv, le tramway et la grande roue.<\/em><\/p>\n<p>\u00c0 l&#8217;\u00e9poque de l&#8217;URSS, Kharkiv \u00e9tait la capitale de la R\u00e9publique socialiste sovi\u00e9tique d\u2019Ukraine et elle portait le nom de Kharkov.<\/p>\n<p>Lorsque nous nous sommes promen\u00e9s dans la ville, nous avons tout de suite vu les diff\u00e9rences d&#8217;influence entre Lviv et Kharkiv. \u00c0 Lviv, l&#8217;architecture a \u00e9t\u00e9 influenc\u00e9e par les Autrichiens et les Polonais, alors qu&#8217;\u00e0 Kharkiv, c&#8217;est principalement l&#8217;architecture sovi\u00e9tique qui domine.<\/p>\n<p>Lors de notre s\u00e9jour, nous avons rendu visite \u00e0 Artem qui est un ami et ancien coll\u00e8gue de ma compagne. Il nous a invit\u00e9s \u00e0 d\u00e9couvrir le village o\u00f9 habitent ses parents et o\u00f9 il a grandi : le village de Dvorichna ainsi que le parc national Dvorichansky.<\/p>\n<p>Nous avons donc pris un bus depuis Kharkiv pour rejoindre Dvorichna. Habituellement, le trajet dure 2h10 mais la veille de notre d\u00e9part, un avion militaire s&#8217;\u00e9tait crash\u00e9 sur notre itin\u00e9raire. Nous avons mis plus de 3h30 \u00e0 rejoindre le village. Sur la route, des agricultrices vendaient leur r\u00e9colte du jour.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items masonry-items\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2080-600x400.png\" width=\"600\" height=\"400\" alt=\"Des vendeuses sur le bord de la route\" title=\"Des vendeuses sur le bord de la route\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2080.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2100-600x400.png\" width=\"600\" height=\"400\" alt=\"Le pont\" title=\"Le pont\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2100.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2092-600x400.png\" width=\"600\" height=\"400\" alt=\"Paysage Ukrainien\" title=\"Paysage Ukrainien\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2092.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>D\u00e9couverte de Dvorichna<\/em><\/p>\n<p>\u00c0 notre arriv\u00e9e \u00e0 Dvorichna, son papa est venu nous chercher en voiture et nous a conduits chez eux o\u00f9 sa maman avait pr\u00e9par\u00e9 un festin ! Nous avons notamment eu droit \u00e0 un bol de bortsch, une soupe traditionnelle Ukrainienne.<\/p>\n<p>Apr\u00e8s le repas, Artem et son papa nous ont fait d\u00e9couvrir le parc national Dvorichansky et nous nous sommes arr\u00eat\u00e9s \u00e0 une carri\u00e8re de craie. Nous avons \u00e9galement fait une pause dans un village o\u00f9 il est plus rapide de passer par un pont suspendu pour aller faire ses courses (10 min) que de prendre la voiture (1h30).<\/p>\n<p>Ma compagne \u00e9tant d\u00e9j\u00e0 venue rendre visite \u00e0 cette famille, elle savait que l&#8217;un des anciens professeur d&#8217;Artem \u00e9tait apiculteur et qu&#8217;il vendait du miel &#8220;fait maison&#8221;. Nous lui avons donc rendu visite et nous lui avons achet\u00e9 2 litres de miel pour 150 UAH (soit 4.40 euros !)<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesimage_grid\" data-onclick=\"link_image\" data-interval=\"5\">\r\n\r\n\t<div class=\"portfolio-wrap\">\r\n\t\t\t\r\n\t\t\t<span class=\"portfolio-loading\"><\/span>\r\n\r\n\t\t\t<div class=\"row portfolio-items masonry-items\" data-starting-filter=\"\" data-gutter=\"5px\" data-masonry-type=\"default\" data-bypass-cropping=\"\"  data-ps=\"5\" data-categories-to-show=\"\" data-col-num=\"cols-3\">\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\r\n\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2081-600x400.png\" width=\"600\" height=\"400\" alt=\"Le Borscht, une soupe Ukrainienne\" title=\"Le Borscht, une soupe Ukrainienne\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2081.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2084-600x400.png\" width=\"600\" height=\"400\" alt=\"Les ruches\" title=\"Les ruches\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2084.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"col span_4 regular element\" data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"none\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"work-item style-3-alt\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2737-600x400.png\" width=\"600\" height=\"400\" alt=\"Le miel\" title=\"Le miel\" \/>\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"work-info-bg\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"work-info\">\r\n    \t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"vert-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!--\/vert-center-->\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2737.png\" class=\"pretty_photo\"><\/a>\r\n\t\t\t\t\t\t\t\t   \t\t\r\n\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!--work-item-->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t<\/div><\/div> \r\n\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Le Bortsch pr\u00e9par\u00e9 par la maman de Artem et le miel que vend son ancien professeur.<\/em><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>VII \u2013 Notre passage \u00e0 Kiev<\/h2>\n<p>Apr\u00e8s notre s\u00e9jour \u00e0 Kharkiv, nous avons repris un train de nuit en direction de Lviv mais nous avons fait escale pendant 3 jours \u00e0 Kiev, la capitale de l&#8217;Ukraine.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2153.png\" class=\"pp center\">\r\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"4032\" width=\"3024\" data-animation=\"fade-in\" src=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2153.png\" alt=\"\" srcset=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2153.png 3024w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2153-300x400.png 300w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2153-225x300.png 225w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2153-768x1024.png 768w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2153-1152x1536.png 1152w, https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2021\/02\/IMG_2153-1536x2048.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: center;\"><em>Un autre train nuit pour Kiev<\/em><\/p>\n<p>Malheureusement, nous n&#8217;avons pas eu le temps de visiter Kiev : nous nous y sommes principalement arr\u00eat\u00e9s afin de visiter et de d\u00e9couvrir l&#8217;histoire de Prypiat, la ville qui a \u00e9t\u00e9 \u00e9vacu\u00e9e suite \u00e0 la catastrophe de Tchernobyl.<\/p>\n<p>Je reviendrai en d\u00e9tail sur cette visite incroyable dans un prochain article.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>VIII \u2013 Informations pratiques Ukraine<\/h2>\n<h4>FORMALIT\u00c9S D\u2019ENTR\u00c9E<\/h4>\n<p><em><strong>Visa :<br \/>\n<\/strong><\/em><span style=\"color: #339966;\"><strong>PAS BESOIN DE VISA<\/strong>, pour les Fran\u00e7ais qui souhaitent faire du tourisme pendant moins de 90 jours<\/span><em><strong><br \/>\n<\/strong><\/em><\/p>\n<p><em><strong>Dur\u00e9e de vol direct depuis Paris vers Kiev :<br \/>\n<\/strong><\/em>3 heures et 10 minutes<\/p>\n<p><em><strong>Dur\u00e9e de vol direct depuis Paris vers Lviv :<br \/>\n<\/strong><\/em>2 heures et 30 minutes<\/p>\n<p><em><strong>D\u00e9calage horaire :<\/strong><\/em><br \/>\n+ 1 heure<\/p>\n<h4>BUDGET &amp; CHANGE<\/h4>\n<p><em><strong>H\u00e9bergement :<\/strong><\/em><\/p>\n<p>Prix moyen d\u2019une chambre avec un lit double dans un h\u00f4tel 1 \u00e0 3 \u00e9toiles :\u00a0<strong>En moyenne 1016 UAH la nuit soit environ 30 euros.<\/strong><br \/>\nPrix moyen d\u2019une chambre avec un lit double dans un h\u00f4tel 4 \u00e0 5 \u00e9toiles :\u00a0<strong>En moyenne 4287 UAH la nuit soit environ 125 euros.<\/strong><\/p>\n<p><em>Les prix peuvent bien s\u00fbr varier en fonction de la saison.<\/em><\/p>\n<p><em><strong>Restaurants :<\/strong><\/em><\/p>\n<p>\u2013\u00a0<em><strong>Menu de Fast Food :<\/strong><\/em> environ 104 UAH (3.50 \u20ac)<br \/>\n\u2013\u00a0<em><strong>Restaurant Classique :<\/strong><\/em> environ 120 UAH (3.52 \u20ac)<br \/>\n\u2013\u00a0<em><strong>Restaurant Chic :\u00a0<\/strong><\/em> \u00e0 partir de 300 UAH (8.80 \u20ac)<\/p>\n<p><em><strong>Devise :<\/strong><\/em><\/p>\n<p>En Ukraine, la monnaie est l&#8217;Hryvnia Ukrainien (UAH).<\/p>\n<p>Aucun probl\u00e8me pour trouver des distributeurs de billets Visa ou Mastercard, ni pour payer par carte bancaire dans la plupart des commerces.<\/p>\n<h4>CLIMAT<\/h4>\n<p>Avec une superficie de 603 700 km\u00b2, l&#8217;Ukraine est le deuxi\u00e8me pays le plus grand d&#8217;Europe : il b\u00e9n\u00e9ficie d&#8217;un climat continental avec des hivers tr\u00e8s froids et des \u00e9t\u00e9s qui sont de plus en plus chaud en vous dirigeant vers le sud du pays.<\/p>\n<p>En hiver, les temp\u00e9ratures ne d\u00e9passent que tr\u00e8s rarement z\u00e9ro (sauf en Crim\u00e9e). \u00c0 Kiev, il neige en moyenne 80 jours par an.<\/p>\n<p>Au printemps, les temp\u00e9ratures et l&#8217;ensoleillement augmentent rapidement .<\/p>\n<p>En \u00e9t\u00e9 il fait chaud et ensoleill\u00e9 mais des orages sont possibles.<\/p>\n<p>Enfin, \u00e0 l&#8217;automne les temp\u00e9ratures d\u00e9gringolent rapidement. Les premi\u00e8res journ\u00e9es froides, avec les premi\u00e8res chutes de neige dans le centre-nord, peuvent se produire d\u00e8s le mois d&#8217;octobre. En novembre il fait froid dans tout le pays et le soleil se fait rare.<\/p>\n<p><em><strong>Meilleurs mois :<\/strong><\/em><\/p>\n<p>Les meilleurs mois pour visiter l&#8217;Ukraine sont d&#8217;avril \u00e0 fin septembre avec une temp\u00e9rature constante de 26 degr\u00e9s Celsius en moyenne.<\/p>\n<h4>SANT\u00c9<\/h4>\n<p>D&#8217;apr\u00e8s l&#8217;OMS, le syst\u00e8me de sant\u00e9 Ukrainien est class\u00e9 79\u00e8me sur 191. N&#8217;ayant pas eu besoin de consulter un m\u00e9decin ou d&#8217;aller \u00e0 l&#8217;h\u00f4pital en Ukraine, je ne peux pas donner mon point de vue.<\/p>\n<p>Je vous recommande de toujours voyager en \u00e9tant assur\u00e9 pour la sant\u00e9.<\/p>\n<p><em><strong>Vaccins recommand\u00e9s :\u00a0<\/strong><\/em><a href=\"https:\/\/www.pasteur.fr\/fr\/centre-medical\/preparer-son-voyage\/ukraine\">Consulter le site de l\u2019Institut Pasteur<\/a><\/p>\n<h4>S\u00c9CURIT\u00c9<\/h4>\n<p>L&#8217;Ukraine est actuellement en guerre dans la partie Est du pays : \u00e9videmment il est strictement d\u00e9conseill\u00e9 (voir interdit) de se rendre dans la zone de conflit.<\/p>\n<p>Dans les villes que nous avons visit\u00e9es, nous ne nous sommes sentis en danger \u00e0 aucun moment. Les recommandations habituelles en termes de s\u00e9curit\u00e9 continuent de s\u2019appliquer bien entendu.<\/p>\n<h4>INTERNET<\/h4>\n<p>Dans les zones touristiques et les villes, la connexion internet n\u2019est pas un probl\u00e8me. Pas de censure particuli\u00e8re \u00e0 ma connaissance.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>IX \u2013 La carte<\/h2>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div id=\"map_6a046671c537b\" style=\"height: 400px;\" class=\"nectar-leaflet-map\" data-infowindow-start-open=\"\" data-dark-color-scheme=\"\" data-marker-style=\"default\" data-nectar-marker-color=\"extra-color-1\" data-ultra-flat=\"\" data-greyscale=\"\" data-extra-color=\"\" data-enable-animation=\"false\" data-enable-zoom=\"\" data-zoom-level=\"6\" data-center-lat=\"49.482522832893295\" data-center-lng=\"31.39521472585957\" data-marker-img=\"\"><\/div><div class=\"map_6a046671c537b map-marker-list\"><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"49.840167074896094 \" data-lng=\" 24.026325679989966 \" data-mapinfo=\" Lviv<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"50.4411933882337 \" data-lng=\" 30.538155432339288 \" data-mapinfo=\" Kiev<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"49.98076552943252 \" data-lng=\" 36.26106843101918 \" data-mapinfo=\" Kharkiv<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"51.27470545842298 \" data-lng=\" 30.220082801799787 \" data-mapinfo=\" Tchernobyl<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"51.40600099588379 \" data-lng=\" 30.053406155512594 \" data-mapinfo=\" Pripiat<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"49.69128561742099 \" data-lng=\" 24.648682450483598 \" data-mapinfo=\" Lypivtsi<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"49.68251553952911 \" data-lng=\" 24.712790465995877 \" data-mapinfo=\" Plenykiv<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"49.84389892894623 \" data-lng=\" 24.026331729852696 \" data-mapinfo=\" Op\u00e9ra de Lviv<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"49.841712598557166 \" data-lng=\" 24.032873136480983 \" data-mapinfo=\" Lviv Coffee Manufacture<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"49.84309537411116 \" data-lng=\" 24.031597994919597 \" data-mapinfo=\" Restaurant Gas Lamp<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"49.840707858961 \" data-lng=\" 24.03491098281112 \" data-mapinfo=\" Gwara Delicatessen<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"49.84136588168184 \" data-lng=\" 24.032102964919666 \" data-mapinfo=\" Kryivka<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"50.017370193506046 \" data-lng=\" 36.244823257721976 \" data-mapinfo=\" Parc Kharkiv<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"49.842370098209756 \" data-lng=\" 24.032587188642548 \" data-mapinfo=\" Fifth Dungeon<br \/>\"><\/div><div class=\"map-marker\" data-marker-image-width=\"50\" data-marker-image-height=\"50\" data-lat=\"49.84767563019262 \" data-lng=\" 24.0156920632643 \" data-mapinfo=\" Le Centre Culturel de la Bi\u00e8re Lvivarnya\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2>X \u2013 Conclusion<\/h2>\n<p>Je ne savais pas vraiment \u00e0 quoi m&#8217;attendre avant d&#8217;arriver en Ukraine : je ne connaissais que tr\u00e8s peu ce pays.<\/p>\n<p>J&#8217;ai d\u00e9couvert une culture int\u00e9ressante et riche ainsi qu&#8217;une population tr\u00e8s accueillante. Nous avons d\u00e9j\u00e0 envie de retourner en Ukraine, tr\u00e8s probablement lorsque la vie reviendra \u00e0 la normale un peu partout, et pourquoi pas m\u00eame investir \u00e0 Lviv.<\/p>\n<p>D&#8217;ailleurs, durant mon s\u00e9jour en Ukraine, j&#8217;ai \u00e9tudi\u00e9 le march\u00e9 immobilier de Lviv, si c&#8217;est un sujet qui vous int\u00e9resse, <a href=\"https:\/\/guillaumeteillet.com\/en\/immobilier-en-ukraine-je-vous-partage-mes-recherches\/\">j&#8217;ai \u00e9crit un article \u00e0 ce sujet (cliquez ici)<\/a>.<\/p>\n<p>Si vous ne connaissez pas encore l&#8217;Ukraine, Lviv est tr\u00e8s certainement la premi\u00e8re ville que vous devriez visiter !<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Dans cet article, je vais vous parler des trois mois que j'ai pass\u00e9 en Ukraine : fin Ao\u00fbt 2020, je me suis install\u00e9 \u00e0 Lviv en Ukraine afin de d\u00e9couvrir...","protected":false},"author":1,"featured_media":7132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-7114","post","type-post","status-publish","format-standard","has-post-thumbnail","category-voyages"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\ud83c\uddfa\ud83c\udde6 Ma vie en Ukraine - Guillaume TEILLET<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guillaumeteillet.com\/en\/ma-vie-en-ukraine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\uddfa\ud83c\udde6 Ma vie en Ukraine - Guillaume TEILLET\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guillaumeteillet.com\/en\/ma-vie-en-ukraine\/\" \/>\n<meta property=\"og:site_name\" content=\"Guillaume TEILLET\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-08T07:00:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-01T22:08:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guillaume Teillet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guillaume Teillet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/\",\"url\":\"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/\",\"name\":\"\ud83c\uddfa\ud83c\udde6 Ma vie en Ukraine - Guillaume TEILLET\",\"isPartOf\":{\"@id\":\"https:\/\/guillaumeteillet.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-scaled.jpg\",\"datePublished\":\"2021-02-08T07:00:52+00:00\",\"dateModified\":\"2021-02-01T22:08:45+00:00\",\"author\":{\"@id\":\"https:\/\/guillaumeteillet.com\/#\/schema\/person\/27fe48f08db74c8dee381b5f2277534f\"},\"breadcrumb\":{\"@id\":\"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/#primaryimage\",\"url\":\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-scaled.jpg\",\"contentUrl\":\"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\/\/guillaumeteillet.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ud83c\uddfa\ud83c\udde6 Ma vie en Ukraine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/guillaumeteillet.com\/#website\",\"url\":\"https:\/\/guillaumeteillet.com\/\",\"name\":\"Guillaume TEILLET\",\"description\":\"Cr\u00e9er - Entreprendre - Investir - Partager\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/guillaumeteillet.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/guillaumeteillet.com\/#\/schema\/person\/27fe48f08db74c8dee381b5f2277534f\",\"name\":\"Guillaume Teillet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/guillaumeteillet.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9075bedaaadc1fe3829c3f7f40c99480?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9075bedaaadc1fe3829c3f7f40c99480?s=96&d=mm&r=g\",\"caption\":\"Guillaume Teillet\"},\"sameAs\":[\"https:\/\/www.guillaumeteillet.com\"],\"url\":\"https:\/\/guillaumeteillet.com\/en\/author\/guillaume-teillet\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83c\uddfa\ud83c\udde6 Ma vie en Ukraine - Guillaume TEILLET","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guillaumeteillet.com\/en\/ma-vie-en-ukraine\/","og_locale":"en_US","og_type":"article","og_title":"\ud83c\uddfa\ud83c\udde6 Ma vie en Ukraine - Guillaume TEILLET","og_url":"https:\/\/guillaumeteillet.com\/en\/ma-vie-en-ukraine\/","og_site_name":"Guillaume TEILLET","article_published_time":"2021-02-08T07:00:52+00:00","article_modified_time":"2021-02-01T22:08:45+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-scaled.jpg","type":"image\/jpeg"}],"author":"Guillaume Teillet","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Guillaume Teillet","Est. reading time":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/","url":"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/","name":"\ud83c\uddfa\ud83c\udde6 Ma vie en Ukraine - Guillaume TEILLET","isPartOf":{"@id":"https:\/\/guillaumeteillet.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/#primaryimage"},"image":{"@id":"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-scaled.jpg","datePublished":"2021-02-08T07:00:52+00:00","dateModified":"2021-02-01T22:08:45+00:00","author":{"@id":"https:\/\/guillaumeteillet.com\/#\/schema\/person\/27fe48f08db74c8dee381b5f2277534f"},"breadcrumb":{"@id":"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/#primaryimage","url":"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-scaled.jpg","contentUrl":"https:\/\/guillaumeteillet.com\/wp-content\/uploads\/2020\/09\/IMG_1737-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/guillaumeteillet.com\/ma-vie-en-ukraine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/guillaumeteillet.com\/"},{"@type":"ListItem","position":2,"name":"\ud83c\uddfa\ud83c\udde6 Ma vie en Ukraine"}]},{"@type":"WebSite","@id":"https:\/\/guillaumeteillet.com\/#website","url":"https:\/\/guillaumeteillet.com\/","name":"Guillaume TEILLET","description":"Cr\u00e9er - Entreprendre - Investir - Partager","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guillaumeteillet.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/guillaumeteillet.com\/#\/schema\/person\/27fe48f08db74c8dee381b5f2277534f","name":"Guillaume Teillet","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/guillaumeteillet.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9075bedaaadc1fe3829c3f7f40c99480?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9075bedaaadc1fe3829c3f7f40c99480?s=96&d=mm&r=g","caption":"Guillaume Teillet"},"sameAs":["https:\/\/www.guillaumeteillet.com"],"url":"https:\/\/guillaumeteillet.com\/en\/author\/guillaume-teillet\/"}]}},"_links":{"self":[{"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/posts\/7114"}],"collection":[{"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/comments?post=7114"}],"version-history":[{"count":88,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/posts\/7114\/revisions"}],"predecessor-version":[{"id":8271,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/posts\/7114\/revisions\/8271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/media\/7132"}],"wp:attachment":[{"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/media?parent=7114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/categories?post=7114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guillaumeteillet.com\/en\/wp-json\/wp\/v2\/tags?post=7114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}